{"id":2441,"date":"2021-03-25T13:10:22","date_gmt":"2021-03-25T12:10:22","guid":{"rendered":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b-2\/"},"modified":"2025-07-07T16:01:51","modified_gmt":"2025-07-07T14:01:51","slug":"assurance-auto-tout-savoir-sur-les-permis-b","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/","title":{"rendered":"Assurance auto : tout savoir sur les permis B"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Vous souhaitez passer votre permis de conduire de cat\u00e9gorie B ? Si vous souhaitez en savoir plus sur les permis B, cet article est fait pour vous !<\/p>\n<p><i>\u00c0 savoir : <\/i><i>selon la l\u00e9gislation fran\u00e7aise, <\/i><i>pour chaque <\/i><i>type de permis de conduire<\/i><i>, vous <\/i><i>devrez passer une \u00e9preuve th\u00e9orique (Code de la Route) et une \u00e9preuve pratique.<\/i><\/p>\n<h2>Les permis de cat\u00e9gorie B : quel v\u00e9hicule peut-on conduire ?<\/h2>\n<p>Le permis B vous autorise \u00e0 conduire une voiture ou une camionnette dont le Poids Total Autoris\u00e9 en Charge Total (PTAC) ne d\u00e9passe pas 3,5 tonnes et avec un attelage n\u2019exc\u00e9dant pas 750kg.<\/p>\n<p>Par ailleurs, le permis B permet de conduire les v\u00e9hicules automobiles affect\u00e9s au transport de personnes ou de marchandises et con\u00e7us pour le transport de 9 personnes au total (conducteur compris).<\/p>\n<p>Le permis B poss\u00e8de plusieurs d\u00e9clinaisons.<\/p>\n<h2>Le permis B1<\/h2>\n<p>Il permet de conduire un quadricycle lourd \u00e0 moteur dont la vitesse ne d\u00e9passe pas 60 km\/h et dont le poids \u00e0 vide est inf\u00e9rieur \u00e0 550 kg.<\/p>\n<p>Le permis B1 est souvent utilis\u00e9 pour le transport de marchandises. Cependant, les v\u00e9hicules de plus de 400 kg sont plus g\u00e9n\u00e9ralement utilis\u00e9s pour le transport de personnes.<\/p>\n<p>Pour passer le permis B1, il faut \u00eatre \u00e2g\u00e9 de 16 ans minimum et disposer de l\u2019ASSR.<\/p>\n<h2>Le permis BVA<\/h2>\n<p>Le permis BVA permet de conduire un v\u00e9hicule avec une boite de vitesses automatique.<\/p>\n<p><i>\u00c0 savoir : une mention restrictive indique sur le permis que le <\/i><i>conducteur <\/i><i>a effectu\u00e9 sa formation uniquement pour ce type de v\u00e9hicule.<\/i><\/p>\n<p>Aussi, pour passer le permis BVA, vous devez \u00eatre \u00e2g\u00e9 de 17 ans et demi pour la conduite accompagn\u00e9e ou de 18 ans.<\/p>\n<h3>Passer le permis BVA<\/h3>\n<p>Pour passer le permis BVA, le nombre d\u2019heures de formation est de 13 heures.<\/p>\n<p>L&rsquo;examen pratique se d\u00e9roule dans une voiture \u00e0 bo\u00eete de vitesses automatique.<\/p>\n<p><i>\u00c0 savoir :\u00a0 il est interdit de conduire une voiture avec un levier de vitesse manuel lorsque vous n\u2019\u00eates possesseur que d\u2019un permis BVA.<\/i><\/p>\n<h2>Le permis BE<\/h2>\n<p>Le permis BE autorise la conduite d\u2019une voiture attel\u00e9e \u00e0 une remorque ou une semi-remorque. Leur poids total est sup\u00e9rieur \u00e0 750 kg et inf\u00e9rieur \u00e0 3,5 T. Et dont la somme PTAC de la voiture et de la remorque d\u00e9passe 4,25 T.<\/p>\n<p>Pour passer le permis BE, il faut \u00eatre titulaire du permis B.<\/p>\n<h3>Passer son permis B et BE<\/h3>\n<p>Pour passer son permis B et BE, il faut passer 2 examens :<\/p>\n<ol>\n<li aria-level=\"1\">L\u2019Examen Th\u00e9orique G\u00e9n\u00e9ral (ETG) ou Code de la Route. Le candidat doit r\u00e9pondre \u00e0 40 questions avec au moins 35 r\u00e9ponses justes.<\/li>\n<\/ol>\n<p>L\u2019examen de conduite : cet examen comprend une formation d\u2019un minimum de 20h. L\u2019\u00e9preuve se d\u00e9roule pendant environ 30 minutes sur un parcours avec un examinateur \u00e0 l\u2019int\u00e9rieur du v\u00e9hicule.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Vous souhaitez passer votre permis de conduire de cat\u00e9gorie B ? Si vous souhaitez en savoir plus sur les permis B, cet article est fait pour vous ! \u00c0 savoir : selon la l\u00e9gislation fran\u00e7aise, pour chaque type de permis de conduire, vous devrez passer une \u00e9preuve th\u00e9orique (Code de la Route) et une \u00e9preuve [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assurance auto : tout savoir sur les permis B - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"On conna\u00eet tous le permis B ou permis auto mais peu de personnes savent qu&#039;il en existe plusieurs. D\u00e9couvrez-tout dans cet article.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurance auto : tout savoir sur les permis B - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"On conna\u00eet tous le permis B ou permis auto mais peu de personnes savent qu&#039;il en existe plusieurs. D\u00e9couvrez-tout dans cet article.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-25T12:10:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:01:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/\",\"name\":\"Assurance auto : tout savoir sur les permis B - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2021-03-25T12:10:22+00:00\",\"dateModified\":\"2025-07-07T14:01:51+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"On conna\\u00eet tous le permis B ou permis auto mais peu de personnes savent qu'il en existe plusieurs. D\\u00e9couvrez-tout dans cet article.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-auto-tout-savoir-sur-les-permis-b\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2441"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=2441"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2441\/revisions"}],"predecessor-version":[{"id":2661,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2441\/revisions\/2661"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=2441"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=2441"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=2441"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}