{"id":2451,"date":"2021-04-10T08:27:26","date_gmt":"2021-04-10T06:27:26","guid":{"rendered":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse-2\/"},"modified":"2025-07-07T16:01:52","modified_gmt":"2025-07-07T14:01:52","slug":"conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/","title":{"rendered":"Conseils assurance auto : tout savoir sur les exc\u00e8s de vitesse"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Vous aimeriez passer votre permis de conduire ? Vous souhaitez en savoir plus sur les exc\u00e8s de vitesse et les sanctions ? Nous vous disons tout dans cet article. Bonne lecture !<\/p>\n<h2>L\u2019exc\u00e8s de vitesse : une infraction<\/h2>\n<p>L\u2019exc\u00e8s de vitesse est une infraction du code de la route tr\u00e8s fr\u00e9quemment verbalis\u00e9e.<\/p>\n<h3>Exc\u00e8s de vitesse et sanctions : que risque le conducteur ?<\/h3>\n<p>Le conducteur peut perdre des points\u00a0 en fonction de l\u2019importance de l\u2019exc\u00e8s de vitesse :<\/p>\n<ol>\n<li>Lorsque le d\u00e9passement est compris entre 20 et 30 km\/h, le conducteur perd 2 points.<\/li>\n<li>Entre 30 et 40 km\/h, le conducteur perd 3 points.<\/li>\n<li>Enfin, entre 40 et 50 km\/h, le conducteur perd 4 points.<\/li>\n<li>Si l&rsquo;exc\u00e8s de vitesse est sup\u00e9rieur \u00e0 50 km\/h, l&rsquo;automobiliste perd 6 points sur son permis.<\/li>\n<\/ol>\n<h3>Les amendes suite \u00e0 un exc\u00e8s de vitesse<\/h3>\n<p>Le tarif d\u2019une amende est proportionnel \u00e0 la gravit\u00e9 de l\u2019infraction.<\/p>\n<p>En cas d\u2019infraction de 3\u00e8me classe, ce qui est uniquement le cas des d\u00e9passements de vitesse inf\u00e9rieurs \u00e0 20 km\/h hors agglom\u00e9ration, le conducteur recevra une amende forfaitaire de 68 euros ou 45 euros minor\u00e9e, 180 euros major\u00e9e et 450 euros maximum.<\/p>\n<p>Tous les autres exc\u00e8s de vitesse sont des infractions de 4\u00e8me classe, ce qui explique la s\u00e9v\u00e9rit\u00e9 des sanctions. L\u2019amende forfaitaire \u00e0 payer est syst\u00e9matiquement de 135 euros ou 90 euros minor\u00e9e, 375 euros major\u00e9e ou 750 euros maximum.<\/p>\n<p>Seuls les d\u00e9passements de vitesse sup\u00e9rieurs ou \u00e9gaux \u00e0 50 km\/h sont des infractions de 5\u00e8me classe. Les conducteurs s\u2019exposent \u00e0 une amende maximale de 1 500 euros.<\/p>\n<p>La r\u00e9cidive d\u2019exc\u00e8s de vitesse de plus de 50 km\/h \u00e9tant un d\u00e9lit, elle entra\u00eene une amende maximale de 3 750 euros.<\/p>\n<h2>\u00c0 savoir<\/h2>\n<p>En cas de contr\u00f4le radar fixe ou radar mobile flashant un automobiliste en exc\u00e8s de vitesse, les forces de l\u2019ordre tol\u00e8rent une marge d\u2019erreur par rapport \u00e0 la vitesse retenue par le radar. En effet, les radars fixes ont une tol\u00e9rance de 5 km\/h pour les vitesses inf\u00e9rieures \u00e0 100 km\/h et de 5 km\/h pour des vitesses sup\u00e9rieures \u00e0 100 km\/h. Cela signifie que les radars automatiques ne se d\u00e9clenchent qu\u2019\u00e0 56 km\/h pour une vitesse limit\u00e9e \u00e0 50 km\/h car la vitesse de 51 km\/h sera retenue.<\/p>\n<p>De la m\u00eame fa\u00e7on pour les autres limitations, il y aura d\u00e9clenchement \u00e0 96 km\/h pour une limitation fix\u00e9e \u00e0 90km\/h \u00e0 titre d\u2019exemple. De m\u00eame, au-del\u00e0 de 100 km\/h, le radar fixe se d\u00e9clenche \u00e0 106 km\/h ou, par exemple, \u00e0 138 km\/h en cas de limitation \u00e0 130 km\/h. Les radars mobiles, eux, ont une tol\u00e9rance de 10 km\/h jusqu\u2019\u00e0 100 km\/h et 10 % au-dessus.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][sgnx_spacer spacer_size=\u00a0\u00bbsgnx-spacer&#8211;sm\u00a0\u00bb][vc_video link=\u00a0\u00bbhttps:\/\/youtu.be\/vaZKeYuNmOY\u00a0\u00bb][sgnx_spacer spacer_size=\u00a0\u00bbsgnx-spacer&#8211;sm\u00a0\u00bb][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Vous aimeriez passer votre permis de conduire ? Vous souhaitez en savoir plus sur les exc\u00e8s de vitesse et les sanctions ? Nous vous disons tout dans cet article. Bonne lecture ! L\u2019exc\u00e8s de vitesse : une infraction L\u2019exc\u00e8s de vitesse est une infraction du code de la route tr\u00e8s fr\u00e9quemment verbalis\u00e9e. Exc\u00e8s de vitesse [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conseils assurance auto : tout savoir sur les exc\u00e8s de vitesse - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"A quelles sanctions vous exposez-vous en cas d&#039;exc\u00e8s de vitesse ? Votre assurance auto vous dit tout dans cet article.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conseils assurance auto : tout savoir sur les exc\u00e8s de vitesse - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"A quelles sanctions vous exposez-vous en cas d&#039;exc\u00e8s de vitesse ? Votre assurance auto vous dit tout dans cet article.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-10T06:27:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:01:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"2 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/\",\"name\":\"Conseils assurance auto : tout savoir sur les exc\\u00e8s de vitesse - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2021-04-10T06:27:26+00:00\",\"dateModified\":\"2025-07-07T14:01:52+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"A quelles sanctions vous exposez-vous en cas d'exc\\u00e8s de vitesse ? Votre assurance auto vous dit tout dans cet article.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/conseils-assurance-auto-tout-savoir-sur-les-exces-de-vitesse\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2451"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=2451"}],"version-history":[{"count":2,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2451\/revisions"}],"predecessor-version":[{"id":3379,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2451\/revisions\/3379"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=2451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=2451"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=2451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}