{"id":2946,"date":"2021-06-22T13:26:30","date_gmt":"2021-06-22T11:26:30","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/"},"modified":"2025-07-07T16:02:05","modified_gmt":"2025-07-07T14:02:05","slug":"tout-savoir-sur-la-loi-madelin-et-ses-specificites","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/","title":{"rendered":"Tout savoir sur la loi Madelin et ses sp\u00e9cificit\u00e9s"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Si vous \u00eates travailleur ind\u00e9pendant, vous pouvez b\u00e9n\u00e9ficier de la loi Madelin afin de profiter d\u2019une meilleure couverture sociale, que ce soit en cas de maladie, de perte d\u2019emploi ou pour mieux pr\u00e9parer votre retraite. Quels sont les diff\u00e9rents contrats Loi Madelin dont un autoentrepreneur peut profiter ?<\/p>\n<h2>Qu\u2019est-ce que la loi Madelin ?<\/h2>\n<p>La loi n\u00b0 94-126, soit la loi Madelin qui date du 11 f\u00e9vrier 1994 permet aux travailleurs ind\u00e9pendants de b\u00e9n\u00e9ficier de la d\u00e9duction fiscale loi Madelin. Ils peuvent d\u00e9duire de leurs cotisations de compl\u00e9ments de retraite et d\u2019assurance pr\u00e9voyance de leur b\u00e9n\u00e9fice imposable. Gr\u00e2ce \u00e0 cet avantage fiscal, ils sont ainsi mieux couverts, et peuvent constituer plus facilement une \u00e9pargne afin de faire face aux al\u00e9as de la vie.<\/p>\n<h2>Qui peut en b\u00e9n\u00e9ficier ?<\/h2>\n<p>Un contrat Madelin est donc un produit d\u2019\u00e9pargne exclusif aux travailleurs non-salari\u00e9s. Vous pouvez souscrire \u00e0 un contrat Madelin quel que soit votre secteur d\u2019activit\u00e9, BIC (b\u00e9n\u00e9fices industriels et commerciaux) ou BNC (b\u00e9n\u00e9fices non commerciaux). Les conjoints collaborateurs peuvent \u00e9galement en b\u00e9n\u00e9ficier.<\/p>\n<h2>Quels sont les diff\u00e9rents contrats ?<\/h2>\n<p>Consultations m\u00e9dicales, forfait hospitalier ou optique, les frais m\u00e9dicaux peuvent peser lourd dans votre budget. En souscrivant \u00e0 une assurance sant\u00e9,\u00a0 vous pouvez compl\u00e9ter les remboursements de la S\u00e9curit\u00e9 sociale et r\u00e9duire le co\u00fbt de vos soins m\u00e9dicaux.<\/p>\n<p>En cas de perte d\u2019emploi contrainte, comme une liquidation judiciaire par exemple, les travailleurs ind\u00e9pendants peuvent aussi b\u00e9n\u00e9ficier d\u2019une indemnisation s\u2019ils ont souscrit un contrat de garantie ch\u00f4mage ou de perte d\u2019emploi Madelin.<\/p>\n<p>Quant aux contrats Madelin de pr\u00e9voyance, ils permettent aux travailleurs non-salari\u00e9s de continuer \u00e0 percevoir un revenu m\u00eame s\u2019ils ne sont plus en mesure d\u2019exercer leur activit\u00e9, en cas d\u2019arr\u00eat de travail ou d\u2019invalidit\u00e9.<\/p>\n<p>Vous pouvez \u00e9galement profiter de la Loi Madelin pour mieux pr\u00e9parer votre retraite. Il existe trois types de contrats retraite :<\/p>\n<ul>\n<li>Le contrat Madelin mono-support qui permet d\u2019investir sur un fond en euros uniquement ;<\/li>\n<li>Le contrat Madelin multi-supports qui permet de diversifier son \u00e9pargne ;<\/li>\n<li>Et le contrat Madelin en points qui transforme l\u2019\u00e9pargne en points retraite.<\/li>\n<\/ul>\n<h2>Comment fonctionne la loi Madelin\u00a0?<\/h2>\n<p>Les cotisations vers\u00e9es dans le cadre d\u2019un contrat Madelin sont d\u00e9ductibles du b\u00e9n\u00e9fice imposable. Le fonctionnement d\u00e9pend du type de contrat souscrit.<\/p>\n<p>Dans le cadre d\u2019un contrat de Loi Madelin pr\u00e9voyance, le plafond des cotisations d\u00e9ductibles est de 3,75 % des revenus, augment\u00e9s de 7% du Plafond Annuel de la S\u00e9curit\u00e9 Sociale (PASS). Le tout ne doit pas exc\u00e9der 8 fois le montant du PASS.<\/p>\n<p>En ce qui concerne la compl\u00e9mentaire retraite, le plafond des cotisations est soit \u00e0 10 % du PASS, soit \u00e0 10 % du b\u00e9n\u00e9fice imposable, limit\u00e9 \u00e0 huit fois le PASS. Ce montant augmente de 15 % du b\u00e9n\u00e9fice compris entre une et huit fois le PASS.<\/p>\n<p>Pour un contrat de perte d\u2019emploi, le plafond est fix\u00e9 \u00e0 1,875 % du b\u00e9n\u00e9fice imposable dans la limite de huit fois le montant annuel du PASS ou 2,5 % du montant annuel du Plafond de la S\u00e9curit\u00e9 Sociale.<\/p>\n<p>Que ce soit pour profiter d\u2019une <u>compl\u00e9mentaire sant\u00e9<\/u> ou d\u2019une retraite plus confortable, les contrats Madelin permettent aux travailleurs non-salari\u00e9s de b\u00e9n\u00e9ficier d\u2019une meilleure protection sociale.<\/p>\n<h2>Comment r\u00e9cup\u00e9rer votre \u00e9pargne retraite, votre capital avec la loi Madelin\u00a0?<\/h2>\n<p>Il vous suffit de fournir votre attestation de d\u00e9part en retraite. Ensuite, vous recevrez le versement de votre rente dans les mois qui suivent. Dans votre contrat loi Madelin il existera plusieurs types de rentes\u00a0:<\/p>\n<ul>\n<li>Les rentes viag\u00e8res<\/li>\n<li>Les rentes viag\u00e8res simples<\/li>\n<li>Rentes r\u00e9version<\/li>\n<li>Et les rentes \u00e0 annuit\u00e9s garanties<\/li>\n<\/ul>\n<h2>Comment d\u00e9duire sa mutuelle avec la loi Madelin\u00a0?<\/h2>\n<p>On envoie les remboursements des frais de sant\u00e9 par le contrat mutuelle Madelin sur le compte bancaire de l\u2019assur\u00e9. Ce remboursement n\u2019est pas soumis \u00e0 imposition. Il n\u2019est pas soumis \u00e0 des cotisations sociales non plus.<\/p>\n<p>En effet, vos cotisations de mutuelle sont d\u00e9ductibles d\u2019imp\u00f4ts dans la limite d\u2019un plafond fiscal. On calcule celui-ci en fonction de votre revenu imposable de l\u2019ann\u00e9e en cours. On y ajoute un montant forfaitaire.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Si vous \u00eates travailleur ind\u00e9pendant, vous pouvez b\u00e9n\u00e9ficier de la loi Madelin afin de profiter d\u2019une meilleure couverture sociale, que ce soit en cas de maladie, de perte d\u2019emploi ou pour mieux pr\u00e9parer votre retraite. Quels sont les diff\u00e9rents contrats Loi Madelin dont un autoentrepreneur peut profiter ? Qu\u2019est-ce que la loi Madelin ? La [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[16],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tout savoir sur la loi Madelin et ses sp\u00e9cificit\u00e9s - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Loi Madelin et TNS. Les travailleurs non-salari\u00e9s peuvent b\u00e9n\u00e9ficier de la meilleure couverture pour leurs frais de sant\u00e9.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tout savoir sur la loi Madelin et ses sp\u00e9cificit\u00e9s - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Loi Madelin et TNS. Les travailleurs non-salari\u00e9s peuvent b\u00e9n\u00e9ficier de la meilleure couverture pour leurs frais de sant\u00e9.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-22T11:26:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:05+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"4 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/\",\"name\":\"Tout savoir sur la loi Madelin et ses sp\\u00e9cificit\\u00e9s - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2021-06-22T11:26:30+00:00\",\"dateModified\":\"2025-07-07T14:02:05+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Loi Madelin et TNS. Les travailleurs non-salari\\u00e9s peuvent b\\u00e9n\\u00e9ficier de la meilleure couverture pour leurs frais de sant\\u00e9.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/tout-savoir-sur-la-loi-madelin-et-ses-specificites\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2946"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=2946"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2946\/revisions"}],"predecessor-version":[{"id":2949,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/2946\/revisions\/2949"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=2946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=2946"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=2946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}