{"id":3035,"date":"2021-09-27T08:37:27","date_gmt":"2021-09-27T06:37:27","guid":{"rendered":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/"},"modified":"2025-07-07T16:02:09","modified_gmt":"2025-07-07T14:02:09","slug":"bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/","title":{"rendered":"Bris de glace : quelle assurance et quelle prise en charge auto ?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Votre pare-brise est cass\u00e9 ou fissur\u00e9 ? Vous devez le changer rapidement. Non seulement il va entraver votre bonne visibilit\u00e9 au volant, mais vous risquez une amende. Selon la formule choisie de votre assurance auto, une garantie bris de glace peut \u00eatre incluse. Quelles sont les cons\u00e9quences d\u2019une r\u00e9paration de pare-brise sans assurance bris de glace ? Pourquoi est-il judicieux de souscrire cette garantie optionnelle ? Quelle prise en charge du bris de glace par votre assurance auto\u00a0?<\/p>\n<h2>Comment faire r\u00e9parer un pare-brise cass\u00e9 sans assurance bris de glace\u00a0?<\/h2>\n<p>Quel que soit le dommage subi sur votre pare-brise, si vous n\u2019avez pas souscrit une assurance bris de glace, la totalit\u00e9 des frais sera \u00e0 votre charge en cas de sinistre responsable.<\/p>\n<p>Ne tardez pas \u00e0 faire les r\u00e9parations, m\u00eame s\u2019il s\u2019agit d\u2019un petit impact ou d\u2019une fissure superficielle. Il suffit d\u2019une route endommag\u00e9e pour que le bris de glace s\u2019agrandisse et devienne dangereux pour vous et vos passagers. En effet, un impact est facilement r\u00e9parable. Par contre, vous devez remplacer un pare-brise fissur\u00e9.<\/p>\n<p>Attention\u00a0! En fonction de son emplacement, le bris de glace peut g\u00eaner la visibilit\u00e9 du conducteur. De plus, laisser en l\u2019\u00e9tat une fissure de plus de 30\u00a0cm ou qui parcourt la largeur ou la hauteur du pare-brise est interdit par la loi (<u>article R316-3 du Code de la route<\/u>). En cas de contr\u00f4le, vous risquez une contravention de 375 \u20ac. Sans oublier que si vous devez passer votre contr\u00f4le technique, il sera d\u00e9favorable. Vous devez faire les r\u00e9parations avant la contre-visite.<\/p>\n<h3>Comment r\u00e9parer un impact de moins de 2\u00a0cm\u00a0?<\/h3>\n<p>Bien que l\u2019impact soit minime, il est important de faire les r\u00e9parations rapidement. Plus vous attendez, plus vous prenez le risque de devoir le changer\u00a0! Heureusement, un pare-brise est facile \u00e0 r\u00e9parer si l\u2019impact sur votre pare-brise fait moins de 2\u00a0cm. Deux solutions s\u2019offrent alors \u00e0 vous\u00a0:<\/p>\n<ul>\n<li>Le r\u00e9parer vous-m\u00eame \u00e0 l\u2019aide d\u2019un kit sp\u00e9cial\u00a0: vous trouverez des kits de r\u00e9paration pour moins de 50\u00a0\u20ac\u00a0;<\/li>\n<li>Le faire r\u00e9parer par votre garagiste\u00a0: celui-ci injectera une r\u00e9sine sp\u00e9ciale pour combler l\u2019impact. Les tarifs varient autour d\u2019une centaine d\u2019euros.<\/li>\n<\/ul>\n<h3>Quand faut-il remplacer votre pare-brise\u00a0?<\/h3>\n<p>Parfois, les r\u00e9parations ne sont malheureusement pas possibles. Vous devez alors faire changer votre pare-brise si\u00a0:<\/p>\n<ul>\n<li>L\u2019impact fait plus de 2,5\u00a0cm\u00a0;<\/li>\n<li>S\u2019il se situe dans votre champ de vision\u00a0;<\/li>\n<li>Ou s\u2019il se trouve \u00e0 4\u00a0cm du bord\u00a0;<\/li>\n<li>Vous avez plus de trois\u00a0impacts sur votre pare-brise.<\/li>\n<\/ul>\n<p>Sans assurance bris de glace, un remplacement de votre pare-brise vous co\u00fbtera entre 350\u00a0\u20ac et 550\u00a0\u20ac.<\/p>\n<p>Une telle somme peut impacter consid\u00e9rablement votre budget, voici quelques astuces pour \u00e9viter de fissurer votre pare-brise\u00a0:<\/p>\n<ul>\n<li>Privil\u00e9giez les parkings surveill\u00e9s pour \u00e9viter les vols et les infractions\u00a0;<\/li>\n<li>Stationnez aussi votre v\u00e9hicule dans votre garage si vous en poss\u00e9dez un ;<\/li>\n<li>Adaptez votre vitesse et votre conduite sur les routes gravillonn\u00e9es\u00a0;<\/li>\n<li>Prot\u00e9gez votre pare-brise des fortes chaleurs avec un pare-soleil ou garez-vous syst\u00e9matiquement \u00e0 l\u2019ombre\u00a0;<\/li>\n<li>L\u2019hiver, d\u00e9givrez doucement votre pare-brise pour \u00e9viter les chocs thermiques.<\/li>\n<\/ul>\n<h2>Pourquoi choisir une assurance bris de glace\u00a0?<\/h2>\n<p>Choisir une <u>assurance bris de glace<\/u> garantit votre s\u00e9r\u00e9nit\u00e9. Personne n\u2019est \u00e0 l\u2019abri d\u2019un impr\u00e9vu et un bris de glace peut arriver \u00e0 tout instant\u00a0suite \u00e0 :<\/p>\n<ul>\n<li>La projection d\u2019un caillou\u00a0;<\/li>\n<li>Une chauss\u00e9e d\u00e9form\u00e9e\u00a0;<\/li>\n<li>Une chute de gr\u00eale\u00a0;<\/li>\n<li>Un choc avec un autre v\u00e9hicule.<\/li>\n<\/ul>\n<p>Une assurance bris de glace vous couvre en cas d\u2019impact ou de fissure. Vous \u00eates ainsi indemnis\u00e9 pour le sinistre subit.<\/p>\n<p>Cette option est facultative. En assurance auto, la Responsabilit\u00e9 Civile seulement est obligatoire. C\u2019est \u00e0 vous de demander la garantie bris de glace \u00e0 votre assureur ou \u00e0 votre <u>courtier en assurance<\/u>. Vous pouvez la rajouter, que vous soyez assur\u00e9 \u00ab\u2009au tiers\u2009\u00bb ou \u00ab\u2009interm\u00e9diaire\u2009\u00bb. Les contrats auto \u00ab\u2009tous risques\u2009\u00bb proposent toujours cette garantie en inclusion.<\/p>\n<p>Comme c\u2019est une garantie optionnelle, l\u2019assurance bris de glace entra\u00eene des frais suppl\u00e9mentaires. N\u00e9anmoins, au regard des co\u00fbts de r\u00e9paration ou de remplacement d\u2019un pare-brise, elle sera vite amortie\u00a0!<\/p>\n<h3>Avec ou sans franchise\u00a0?<\/h3>\n<p>Si vous avez la possibilit\u00e9 de souscrire une garantie bris de glace sans franchise, votre cotisation sera plus \u00e9lev\u00e9e, mais votre couverture sera \u00e9galement plus importante. Le montant de la franchise varie selon les assureurs et reste un \u00e9l\u00e9ment \u00e0 prendre en compte lorsque vous faites un comparatif des diff\u00e9rentes offres. Bien que la franchise puisse vous sembler \u00e9lev\u00e9e, elle est un choix judicieux\u00a0: les bris de glace \u00e9tant assez fr\u00e9quents, il est parfois pr\u00e9f\u00e9rable de payer un peu plus cher\u00a0!<\/p>\n<h3>Quelles incidences sur le bonus-malus\u00a0?<\/h3>\n<p>La d\u00e9claration d\u2019un bris de glace n\u2019a aucune cons\u00e9quence sur votre malus. Elle n\u2019entra\u00eene ni le gel de votre coefficient de bonus-malus ni de malus. En effet, comme tout sinistre sans tiers, votre pare-brise cass\u00e9 ne peut \u00eatre pris en compte dans le calcul du coefficient de r\u00e9duction &#8211; majoration.<\/p>\n<p>Bon \u00e0 savoir\u00a0: si vous d\u00e9clarez de nombreux bris de glace au cours de l\u2019ann\u00e9e, certains assureurs peuvent revoir \u00e0 la hausse le montant de votre cotisation ou de la franchise bris de glace, et m\u00eame aller jusqu\u2019\u00e0 la r\u00e9siliation de votre contrat d\u2019assurance auto. Parfois, pour des petites r\u00e9parations, il est pr\u00e9f\u00e9rable de ne pas faire marcher son assurance.<\/p>\n<h2>Que couvre l\u2019assurance bris de glace\u00a0?<\/h2>\n<p>En cas de bris de glace, l\u2019assurance couvre l\u2019ensemble des \u00e9l\u00e9ments vitr\u00e9s de votre voiture et prend en charge les frais de remplacement ou de r\u00e9paration des glaces bris\u00e9es ou endommag\u00e9es. N\u00e9anmoins, en fonction de la formule choisie, l\u2019\u00e9tendue de la garantie sera plus ou moins large.<\/p>\n<h3>Les parties du v\u00e9hicule couvertes par la garantie bris de glace<\/h3>\n<p>Il est difficile de donner une liste exacte des parties avec vitre que la garantie bris de glace prend en charge. Celle-ci va d\u00e9pendre de votre assureur et de votre contrat. Toutefois, la garantie de base inclut au minimum la prise en charge du pare-brise.<\/p>\n<p>Selon votre formule, peuvent \u00eatre couverts en plus du pare-brise\u00a0:<\/p>\n<ul>\n<li>Les diff\u00e9rents feux et phares et leur protection\u00a0;<\/li>\n<li>La lunette arri\u00e8re\u00a0;<\/li>\n<li>Les vitres lat\u00e9rales\u00a0;<\/li>\n<li>La vitre du toit ouvrant ou panoramique\u00a0;<\/li>\n<li>Les r\u00e9troviseurs\u00a0;<\/li>\n<li>Les d\u00e9flecteurs de portes.<\/li>\n<\/ul>\n<p>Attention, seules les parties mont\u00e9es en s\u00e9rie par le constructeur de la voiture sont couvertes par l\u2019assurance bris de glace. En outre, vous n&rsquo;avez pas droit \u00e0 indemnisation si le dommage est d\u00fb \u00e0 un d\u00e9faut d\u2019entretien, \u00e0 la v\u00e9tust\u00e9 ou \u00e0 l\u2019usure.<\/p>\n<p>Prenez le temps de bien lire les clauses de votre contrat d\u2019assurance voiture (dans les conditions g\u00e9n\u00e9rales) afin de savoir quelles sont les parties prises en charge en cas de sinistre.<\/p>\n<p>Pour info : demandez \u00e0 votre assureur si les frais de marquage ou de gravage sont bien pris en compte en cas de remplacement d\u2019une vitre concern\u00e9e.<\/p>\n<h3>Les dommages couverts par l\u2019assurance bris de glace<\/h3>\n<p>Les dommages couverts par votre assureur en cas de bris de glace peuvent l\u00e0 encore varier. G\u00e9n\u00e9ralement, le contrat d\u2019assurance \u00e9voque le bris de glace sans plus de pr\u00e9cision.<\/p>\n<p>Sachez n\u00e9anmoins que pour une prise en charge par la garantie bris de glace, le sinistre doit \u00eatre exclusif. Concr\u00e8tement, cela signifie que votre v\u00e9hicule ne doit avoir subi aucun autre sinistre.<\/p>\n<p>Par exemple, dans le cas d&rsquo;une vitre bris\u00e9e pour d\u00e9rober un bien, le sinistre sera alors class\u00e9 comme vol. Ainsi, la garantie bris de glace ne fonctionnera pas. Si les dommages caus\u00e9s sont le fait d\u2019une catastrophe naturelle (gr\u00eale, temp\u00eate\u2026), c\u2019est la garantie affili\u00e9e qui pr\u00e9vaudra.<\/p>\n<h2>Pare-brise cass\u00e9\u00a0: comment faire marcher l\u2019assurance bris de glace\u00a0?<\/h2>\n<p>Dans un premier temps, contactez votre assureur, il vous indiquera alors si\u00a0:<\/p>\n<ul>\n<li>L\u2019assurance bris de glace fait partie de votre contrat ;<\/li>\n<li>Quel sera le montant de la franchise \u00e0 payer apr\u00e8s la r\u00e9paration s\u2019il y a lieu\u00a0;<\/li>\n<li>Si la partie vitr\u00e9e endommag\u00e9e est couverte.<\/li>\n<\/ul>\n<p>Vous avez cinq\u00a0jours ouvr\u00e9s pour d\u00e9clarer le bris de vitre aupr\u00e8s de votre assureur et faire fonctionner l\u2019assurance bris de glace (article L.\u00a0113-2-4 du Code des assurances). Pour cette d\u00e9claration, adressez un courrier en recommand\u00e9 avec accus\u00e9 de r\u00e9ception au service sinistre de votre compagnie d\u2019assurance.<\/p>\n<p>Ensuite, soit\u00a0:<\/p>\n<ul>\n<li>Vous faites r\u00e9parer votre pare-brise par le garagiste de votre choix (avec l\u2019accord de votre compagnie d\u2019assurance), puis vous vous faites rembourser la facture par celle-ci\u00a0;<\/li>\n<li>Votre assureur mandate une entreprise partenaire qu\u2019elle r\u00e9glera elle-m\u00eame. Ainsi cela vous \u00e9vitera une avance de frais et il ne vous restera plus que la franchise \u00e0 honorer.<\/li>\n<\/ul>\n<p>Pour conclure\u00a0: bien qu\u2019elle augmente votre prime d\u2019assurance, souscrire une assurance bris de glace s\u2019av\u00e8re rentable au regard des frais engendr\u00e9s en cas d\u2019impact ou de fissure sur votre pare-brise ou toutes autres surfaces vitr\u00e9es. N\u2019h\u00e9sitez pas \u00e0 comparer les diff\u00e9rents tarifs et formules propos\u00e9s par les assureurs ou faites appel \u00e0 un courtier en assurance\u00a0![\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Votre pare-brise est cass\u00e9 ou fissur\u00e9 ? Vous devez le changer rapidement. Non seulement il va entraver votre bonne visibilit\u00e9 au volant, mais vous risquez une amende. Selon la formule choisie de votre assurance auto, une garantie bris de glace peut \u00eatre incluse. Quelles sont les cons\u00e9quences d\u2019une r\u00e9paration de pare-brise sans assurance bris de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bris de glace : quelle assurance et quelle prise en charge auto ? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Comment r\u00e9parer un impact ou une fissure sur un pare-brise sans avoir d\u2019assurance bris de glace ? D\u00e9couvrez pourquoi il faut en souscrire une\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bris de glace : quelle assurance et quelle prise en charge auto ? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Comment r\u00e9parer un impact ou une fissure sur un pare-brise sans avoir d\u2019assurance bris de glace ? D\u00e9couvrez pourquoi il faut en souscrire une\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-27T06:37:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:09+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"8 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/\",\"name\":\"Bris de glace : quelle assurance et quelle prise en charge auto ? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2021-09-27T06:37:27+00:00\",\"dateModified\":\"2025-07-07T14:02:09+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Comment r\\u00e9parer un impact ou une fissure sur un pare-brise sans avoir d\\u2019assurance bris de glace ? D\\u00e9couvrez pourquoi il faut en souscrire une\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bris-de-glace-quelle-assurance-et-quelle-prise-en-charge-auto\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3035"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3035"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3035\/revisions"}],"predecessor-version":[{"id":3491,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3035\/revisions\/3491"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3035"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}