{"id":3205,"date":"2022-04-15T11:02:10","date_gmt":"2022-04-15T09:02:10","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/fin-de-suspension-de-permis-puis-je-conduire-2\/"},"modified":"2025-07-07T16:02:14","modified_gmt":"2025-07-07T14:02:14","slug":"fin-de-suspension-de-permis-puis-je-conduire","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/","title":{"rendered":"Fin de suspension de permis de conduire, puis-je conduire ?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]La <strong>suspension<\/strong> du <strong>permis conduire<\/strong> est une sanction qui peut \u00eatre d\u00e9cid\u00e9e par le pr\u00e9fet ou par le juge, selon la nature de la suspension. Elle consiste \u00e0 emp\u00eacher un <strong>conducteur<\/strong> de <strong>conduire<\/strong> un v\u00e9hicule pour lequel le <strong>permis<\/strong> est obligatoire, pendant une dur\u00e9e variable selon les circonstances. Il existe la <strong>suspension<\/strong> <strong>administrative<\/strong> et la <strong>suspension<\/strong> <strong>judiciaire<\/strong>. La <strong>suspension judiciaire<\/strong> sanctionne une<strong> infraction<\/strong> au <strong>code route<\/strong> ou au code p\u00e9nal. Elle peut ou ne pas \u00eatre pr\u00e9c\u00e9d\u00e9e d&rsquo;une <strong>suspensio<\/strong>n administrative de <strong>permis<\/strong> de <strong>conduire<\/strong>.<\/p>\n<h2>Suspension administrative du permis de conduire en situation d\u2019infraction<\/h2>\n<h3>Motif de la suspension<\/h3>\n<p>Le sous-pr\u00e9fet ou le pr\u00e9fet peut d\u00e9livrer, \u00e0 titre provisoire, un arr\u00eat\u00e9 de suspension du <strong>permis<\/strong> de <strong>conduire<\/strong> AM ou permis B dans les cas d\u2019<strong>infractions<\/strong> ci-apr\u00e8s :<\/p>\n<ul>\n<li>conduite sous l\u2019<strong>emprise d\u2019\u00e9tat alcoolique<\/strong> ;<\/li>\n<li>refus d\u2019ob\u00e9ir aux v\u00e9rifications de l\u2019\u00e9tat alcoolique du <strong>conducteur <\/strong>;<\/li>\n<li>conduite sous l\u2019<strong>usage de stup\u00e9fiants<\/strong> ;<\/li>\n<li><strong>stup\u00e9fiants refus de se soumettre<\/strong> aux v\u00e9rifications ;<\/li>\n<li><strong>exc\u00e8s vitesse<\/strong> de plus 40 km\/heure ;<\/li>\n<li>en cas d&rsquo;accident de la circulation entra\u00eenant la mort d&rsquo;une personne ou occasionnant un dommage corporel ;<\/li>\n<li>usage du t\u00e9l\u00e9phone tenu en main ;<\/li>\n<li><strong>infraction <\/strong>aux r\u00e8gles de conduite des v\u00e9hicules, de <strong>vitesse<\/strong>, de croisement, de d\u00e9passement, d&rsquo;intersection et de priorit\u00e9s de passage.<\/li>\n<\/ul>\n<h3>Dur\u00e9e de la suspension pour infractions<\/h3>\n<p>De mani\u00e8re g\u00e9n\u00e9rale, la dur\u00e9e maximale de la<strong> suspension<\/strong> est de 6 mois. Elle peut cependant \u00eatre \u00e9tendue sur une ann\u00e9e. La <strong>dur\u00e9e suspension<\/strong> commence le jour o\u00f9 le <strong>conducteur<\/strong> remet son <strong>permis conduire<\/strong> \u00e0 la pr\u00e9fecture.<\/p>\n<p>Le non-respect d&rsquo;une d\u00e9cision de <strong>suspension<\/strong> peut entra\u00eener une peine d&#8217;emprisonnement de 24 mois, d&rsquo;un paiement d\u2019amende de 4 500 \u20ac et d&rsquo;un jugement de confiscation du v\u00e9hicule.<\/p>\n<h3>Contestation d&rsquo;une suspension administrative<\/h3>\n<p>Vous disposez de plusieurs recours. Tout d\u2019abord, initiez un recours gracieux devant le pr\u00e9fet avant tout recours contentieux. Le pr\u00e9fet pourra rendre un r\u00e9f\u00e9r\u00e9 suspension en attendant la sanction du tribunal. Cette mesure provisoire vous permet de conduire en urgence pour raisons professionnelles par exemple, en attendant la proc\u00e9dure. Vous pouvez aussi faire appel \u00e0 un\u00a0avocat du permis de conduire\u00a0sp\u00e9cialis\u00e9 en droit routier pour contester la suspension de votre permis devant le tribunal administratif.<\/p>\n<h3>R\u00e9cup\u00e9ration du permis de conduire \u00e0 la fin d\u2019une suspension de permis<\/h3>\n<p>Dans les cas d\u2019alcool au volant ou d&rsquo;<strong>usage de stup\u00e9fiants<\/strong>, une <strong>visite m\u00e9dicale<\/strong> devant la <strong>commission m\u00e9dicale d\u00e9partementale<\/strong> est obligatoire avant la fin de la <strong>suspension permis conduire<\/strong>. Pour r\u00e9cup\u00e9rer son permis aupr\u00e8s de la pr\u00e9fecture ou sous-pr\u00e9fecture, il faut se munir de la notification de la<strong> suspension annulation permis<\/strong> et de l&rsquo;<strong>avis de la commission m\u00e9dicale<\/strong>.<\/p>\n<h2>Suspension administrative du permis de conduire selon des motifs m\u00e9dicaux<\/h2>\n<h3>Motifs de la suspension administrative pour raison m\u00e9dicale<\/h3>\n<p>Le responsable de la pr\u00e9fecture peut \u00eatre amen\u00e9 \u00e0 suspendre le <strong>permis de conduire<\/strong>, sur avis de la <strong>commission m\u00e9dicale d\u00e9partementale<\/strong>, dans les situations suivantes :<\/p>\n<ul>\n<li>un conducteur qui passe une <strong>visite m\u00e9dicale<\/strong> suite \u00e0 une <strong>invalidation permis conduire<\/strong>, pr\u00e9sente un probl\u00e8me de sant\u00e9, d&rsquo;alcool\u00e9mie ou d&rsquo;<strong>usage de stup\u00e9fiants <\/strong>;<\/li>\n<li>un m\u00e9decin qui d\u00e9clare qu&rsquo;une personne titulaire d&rsquo;un <strong>permis conduire<\/strong> \u00e0 validit\u00e9 limit\u00e9e n&rsquo;est plus apte \u00e0 <strong>conduire<\/strong>.<\/li>\n<\/ul>\n<h3>Dur\u00e9e de la suspension<\/h3>\n<p>La <strong>dur\u00e9e<\/strong> <strong>suspension<\/strong> peut \u00eatre d&rsquo;un an, renouvelable ou non selon l&rsquo;\u00e9tat de sant\u00e9 du <strong>conducteur<\/strong>.<\/p>\n<h3>R\u00e9cup\u00e9ration du permis de conduire \u00e0 la fin de la suspension<\/h3>\n<p>Le <strong>conducteur<\/strong> devra se soumettre \u00e0 une nouvelle <strong>visite m\u00e9dicale<\/strong> devant la <strong>commission m\u00e9dicale d\u00e9partementale<\/strong> pour r\u00e9cup\u00e9rer son <strong>permis conduire<\/strong>. Pour cela, il doit s&rsquo;adresser \u00e0 la pr\u00e9fecture de son d\u00e9partement pour obtenir un rendez-vous.<\/p>\n<h2>Suspension judiciaire du permis de conduire<\/h2>\n<p>La suspension judiciaire du permis de conduire est une sanction prononc\u00e9e par un juge dans un tribunal. Elle peut faire suite \u00e0 une suspension administrative. Dans ce cas, elle se substitue \u00e0 la sanction administrative en prenant en compte la dur\u00e9e de la sanction d\u00e9j\u00e0 effectu\u00e9e. Elle sanctionne une infraction grave au code de la route ou au code p\u00e9nal. De plus, la suspension peut aller jusqu\u2019\u00e0 5 ans en cas de blessures involontaires ou d\u2019homicide. Elle est m\u00eame doubl\u00e9e en cas de r\u00e9cidive.<\/p>\n<p>Parmi ces infractions, on retrouve\u00a0:<\/p>\n<ul>\n<li>la conduite sous l&rsquo;<strong>emprise d\u2019alcool <\/strong>ou avec <strong>usage de stup\u00e9fiants<\/strong> ;<\/li>\n<li>d\u00e9lit de fuite ;<\/li>\n<li>atteinte involontaire \u00e0 la vie ou \u00e0 l&rsquo;int\u00e9grit\u00e9 d\u2019une tierce personne;<\/li>\n<li><strong>stup\u00e9fiants refus soumettre<\/strong> aux d\u00e9pistages ;<\/li>\n<li><strong>conduite sans permis de conduire<\/strong><\/li>\n<li><strong>exc\u00e8s vitesse<\/strong> de plus de 30 km\/h au-dessus de la vitesse maximale autoris\u00e9e ;<\/li>\n<li>l&rsquo;<strong>infraction <\/strong>sur l&rsquo;usage du portable tenu en main.<\/li>\n<\/ul>\n<h3>Dur\u00e9e de la sanction prononc\u00e9e par le tribunal<\/h3>\n<p>La dur\u00e9e maximale de la <strong>suspension judiciaire<\/strong> du <strong>permis conduire<\/strong> est de :<\/p>\n<ul>\n<li>5 ans pour blessures ou homicides involontaires ;<\/li>\n<li>3 ans pour les autres cas.<\/li>\n<\/ul>\n<p>Cette <strong>dur\u00e9e suspension<\/strong> peut \u00eatre doubl\u00e9e surtout en cas de d\u00e9lit de fuite ou de r\u00e9cidive.<\/p>\n<h3>Arrangement possible de la sanction<\/h3>\n<p>Le<strong> tribunal<\/strong> peut accepter d\u2019am\u00e9nager la peine afin de ne pas causer le licenciement du <strong>conducteur <\/strong>lorsque celui-ci n&rsquo;a pas d&rsquo;autres moyens de transport par exemple. On parle g\u00e9n\u00e9ralement de permis blanc.<\/p>\n<p>Cet arrangement n&rsquo;est toutefois pas possible pour les infractions suivantes :<\/p>\n<ul>\n<li>homicide et blessures involontaires ;<\/li>\n<li>d\u00e9g\u00e2t caus\u00e9 \u00e0 autrui ;<\/li>\n<li>mais aussi, d\u00e9lit de fuite ;<\/li>\n<li>conduite malgr\u00e9 une <strong>suspension permis conduire<\/strong>, <strong>r\u00e9tention permis<\/strong> ou une <strong>annulation permis conduire<\/strong> ;<\/li>\n<li>conduite sous un \u00e9tat alcoolique et\/ou <strong>usage stup\u00e9fiants<\/strong> ;<\/li>\n<li><strong>stup\u00e9fiants ou refus de se soumettre<\/strong> aux v\u00e9rifications ;<\/li>\n<li><strong>exc\u00e8s vitesse<\/strong> de plus de 50 km\/h de la vitesse maximale autoris\u00e9e.<\/li>\n<\/ul>\n<h3>R\u00e9cup\u00e9ration du permis de conduire \u00e0 la fin de la suspension<\/h3>\n<p>Pour r\u00e9cup\u00e9rer son <strong>permis<\/strong> \u00e0 la fin de la<strong> suspension<\/strong>, le <strong>conducteur<\/strong> doit s&rsquo;adresser \u00e0 l&rsquo;autorit\u00e9 mentionn\u00e9e sur l&rsquo;imprim\u00e9 r\u00e9f\u00e9rence 7 qui lui a \u00e9t\u00e9 remis lorsqu&rsquo;il a restitu\u00e9 son<strong> permis<\/strong>.<\/p>\n<p><strong>Dans les cas d&rsquo;alcool\u00e9mie ou d&rsquo;usage de stup\u00e9fiants,<\/strong> il faut d&rsquo;abord passer une <strong>visite m\u00e9dicale test<\/strong> devant la <strong>commission m\u00e9dicale d\u00e9partementale<\/strong>. Le<strong> conducteur<\/strong> doit prendre lui-m\u00eame un rendez-vous.<\/p>\n<p>Selon la nature des infractions commises, le nouveau <strong>permis <\/strong>d\u00e9livr\u00e9 peut avoir une<strong> dur\u00e9e<\/strong> limit\u00e9e. \u00c0 l&rsquo;issue de cette p\u00e9riode ou de ce d\u00e9lai, il est \u00e9galement n\u00e9cessaire de repasser une <strong>visite m\u00e9dicale<\/strong> devant la <strong>commission m\u00e9dicale d\u00e9partementale<\/strong>.<\/p>\n<p>M\u00eame en cas de permis suspendu, vous pouvez suivre un\u00a0stage r\u00e9cup\u00e9ration de points\u00a0agr\u00e9\u00e9 pendant une suspension de permis. Vous pouvez effectuer un stage maximum tous les ans. Pour cela, il faut avoir au moins 1 point sur le permis (permis valide) et avoir perdu des points. Une fois la restitution du permis, il sera cr\u00e9dit\u00e9 de 4 points sans exc\u00e9der le plafond de votre capital de points.<\/p>\n<p>Si le stage fait suite \u00e0 une d\u00e9cision de justice, la formation est identique mais ne donne pas lieu \u00e0 une r\u00e9cup\u00e9ration de points.[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]La suspension du permis conduire est une sanction qui peut \u00eatre d\u00e9cid\u00e9e par le pr\u00e9fet ou par le juge, selon la nature de la suspension. Elle consiste \u00e0 emp\u00eacher un conducteur de conduire un v\u00e9hicule pour lequel le permis est obligatoire, pendant une dur\u00e9e variable selon les circonstances. Il existe la suspension administrative et la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Fin de suspension de permis de conduire, puis-je conduire ? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s une suspension de permis, vous pouvez conduire d\u00e8s le lendemain de la fin de la suspension si votre dossier est \u00e0 jour. Zoom.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fin de suspension de permis de conduire, puis-je conduire ? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s une suspension de permis, vous pouvez conduire d\u00e8s le lendemain de la fin de la suspension si votre dossier est \u00e0 jour. Zoom.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-15T09:02:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"6 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/\",\"name\":\"Fin de suspension de permis de conduire, puis-je conduire ? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-04-15T09:02:10+00:00\",\"dateModified\":\"2025-07-07T14:02:14+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Apr\\u00e8s une suspension de permis, vous pouvez conduire d\\u00e8s le lendemain de la fin de la suspension si votre dossier est \\u00e0 jour. Zoom.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/fin-de-suspension-de-permis-puis-je-conduire\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3205"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3205"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3205\/revisions"}],"predecessor-version":[{"id":3536,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3205\/revisions\/3536"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3205"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}