{"id":3256,"date":"2022-08-26T06:01:06","date_gmt":"2022-08-26T04:01:06","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/"},"modified":"2025-07-07T16:02:18","modified_gmt":"2025-07-07T14:02:18","slug":"accident-sans-constat-pourquoi-et-comment-proceder","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/","title":{"rendered":"Accident sans constat : pourquoi et comment proc\u00e9der\u2009?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2><strong>Accident sans constat : quelles sont les origines et comment proc\u00e9der\u2009?<\/strong><\/h2>\n<p>D\u00e9clarer un <strong>accident de voiture<\/strong> n\u2019est pas une obligation. Mais m\u00eame si vous \u00eates la victime, en cas d\u2019<strong>accident o\u00f9 il n\u2019y a pas de constat<\/strong>, votre <strong>assureur <\/strong>est dans l\u2019impossibilit\u00e9 de vous rembourser les dommages. En effet, c\u2019est une d\u00e9marche quasi-obligatoire par les assureurs. C\u2019est essentiel afin d<strong>\u2019<\/strong>aviser rapidement votre <strong>assurance auto <\/strong>et de d\u00e9tailler le d\u00e9roulement de l\u2019<strong>accident de la route <\/strong>pour \u00eatre ensuite indemnis\u00e9. D\u00e9couvrez quelles sont les diff\u00e9rentes situations de l\u2019absence de <strong>preuves<\/strong>, les proc\u00e9dures \u00e0 suivre en cas d\u2019<strong>accident responsable ou non<\/strong>, ainsi que les renseignements que vous pouvez fournir \u00e0 votre <strong>assurance auto<\/strong> lui permettant de d\u00e9finir les torts de chacun.<\/p>\n<h3><strong>Dans quels cas l\u2019accident sans constat peut-il avoir lieu\u2009?<\/strong><\/h3>\n<p>La loi fran\u00e7aise n\u2019oblige pas un sinistr\u00e9 de d\u00e9clarer un<strong> accident<\/strong>, m\u00eame s\u2019il est d\u2019utilit\u00e9 d\u2019en r\u00e9aliser un. Effectivement, remplir un <strong>constat d&rsquo;accident<\/strong> permet de d\u00e9terminer pr\u00e9cis\u00e9ment les faits, et de les communiquer \u00e0 son <strong>assurance auto<\/strong> afin d\u2019obtenir une \u00e9ventuelle <strong>indemnisation des dommages <\/strong>pr\u00e9vue par le contrat d\u2019assurance.<\/p>\n<p>Il existe cependant plusieurs cas o\u00f9 il peut y avoir un <strong>accident o\u00f9 le constat n\u2019a pas pu \u00eatre fait<\/strong>.<\/p>\n<ul>\n<li>Absence du dit document amiable.<\/li>\n<li>Refus de signer de l&rsquo;autre partie.<\/li>\n<li>Fuite du conducteur de l&rsquo;autre v\u00e9hicule.<\/li>\n<\/ul>\n<h3><strong>Quelles solutions pour d\u00e9clarer un sinistre auto lors d\u2019un accident s\u2019il n&rsquo;y a pas de constat\u2009?<\/strong><\/h3>\n<p>Tout d\u00e9pend de l\u2019<strong>accrochage<\/strong>.<\/p>\n<h4><strong>Non-disponibilit\u00e9 du document<\/strong><\/h4>\n<p>Souvent, aucun des deux conducteurs impliqu\u00e9s dans l\u2019<strong>accident voiture <\/strong>ne disposent d&rsquo;un document imprim\u00e9.<\/p>\n<p>Dans ce cas, vous avez deux options pour pouvoir annoncer votre <strong>accident hors document officiel<\/strong> :<\/p>\n<ul>\n<li>Au moins un des deux conducteurs doit poss\u00e9der un Smartphone. Dans ce fait, vous pouvez utiliser l\u2019application e-<strong>constat amiable <\/strong>pour <strong>notifier le sinistre <\/strong>et le communiquer \u00e0 vos assurances respectives. Il d\u00e9tient la m\u00eame valeur juridique que le <strong>constat amiable<\/strong> traditionnel et peut s\u2019av\u00e9rer \u00eatre tr\u00e8s pratique.<\/li>\n<li>Moins pratique peut \u00eatre mais efficace, vous pouvez <strong>r\u00e9diger un constat<\/strong> sur n\u2019importe quel support papier disponible sur place : feuille blanche, carnet\u2026 Il faut y mentionner les informations indispensables des deux parties : noms et pr\u00e9noms, adresses, num\u00e9ro du permis de conduire, d\u00e9nomination des compagnies d\u2019<strong>assurances<\/strong>, conditions de l\u2019<strong>accident voiture<\/strong>, coordonn\u00e9es des \u00e9ventuels t\u00e9moins\u2026<\/li>\n<\/ul>\n<p>Plus vous transmettez de renseignements \u00e0 votre <strong>assurance<\/strong>, plus vous optimisez vos chances d\u2019obtenir un partage \u00e9quitable des torts.<\/p>\n<h4><strong>Le d\u00e9lit de fuite<\/strong><\/h4>\n<p>Pour tout accident o\u00f9 le <strong>conducteur <\/strong>de l\u2019autre <strong>v\u00e9hicule<\/strong> ne s\u2019arr\u00eate pas, il s\u2019agit d\u2019un <strong>d\u00e9lit de fuite<\/strong> aux yeux de la loi que vous soyez victime ou non. Il faut que vous portiez plainte au commissariat, en fournissant le maximum d\u2019informations que vous avez pu r\u00e9colter sur le <strong>v\u00e9hicule<\/strong> et\/ou son <strong>\u00e9chapp\u00e9e<\/strong>:<\/p>\n<ul>\n<li><strong>Num\u00e9ro de plaque d\u2019immatriculation<\/strong>,<\/li>\n<li>\u00e2ge et sexe du <strong>conducteur<\/strong>,<\/li>\n<li>mod\u00e8le et couleur des <strong>v\u00e9hicules<\/strong>,<\/li>\n<li>t\u00e9moignages des usagers de la route, etc.<\/li>\n<\/ul>\n<p>Sans d\u00e9p\u00f4t de plainte, l&rsquo;assurance ne prend pas en compte l&rsquo;absence des renseignements de l&rsquo;autre parti.<\/p>\n<h4><strong>Le refus de signature<\/strong><\/h4>\n<p>Les deux personnes n\u2019arrivent pas \u00e0 se mettre d\u2019accord sur les modalit\u00e9s de l&rsquo;accident de <strong>voiture<\/strong>, et l\u2019un d\u2019eux ne veux pas signer la d\u00e9claration.<\/p>\n<p>Si le parti tiers impliqu\u00e9 dans <strong>le sinistre <\/strong>refuse d\u2019apporter sa version des faits, vous pouvez <strong>r\u00e9diger la d\u00e9claration<\/strong>, et la transmettre \u00e0 votre <strong>assurance auto<\/strong>. Ainsi, vous \u00e9vitez de tomber dans le cadre d\u2019 <strong>accidents sans version \u00e9crite des faits. <\/strong>Ce\u00a0qui vous prive de toute possibilit\u00e9 d\u2019engager votre <strong>indemnisation pr\u00e9vue par votre garantie<\/strong>. De plus, vous devrez payer la franchise pr\u00e9vue par le contrat.<\/p>\n<p>Dans le cas o\u00f9 l\u2019autre automobiliste poursuivrait dans son <strong>refus<\/strong>, vous aurez l\u2019avantage d\u2019\u00eatre le seul \u00e0 d\u00e9montrer votre version des faits. La personne en d\u00e9lit de fuite n\u2019a pas assur\u00e9 la s\u00e9curit\u00e9 du partie adverse. Dans ce cas, vous serez indemnis\u00e9 par la compagnie d\u2019<strong>assurance gr\u00e2ce \u00e0 la responsabilit\u00e9<\/strong> civile de l\u2019autre <strong>conducteur pour les dommages mat\u00e9riels<\/strong><strong> ou corporels<\/strong>.<\/p>\n<p>Il existe des circonstances o\u00f9 l\u2019autre <strong>conducteur<\/strong> accident\u00e9, au d\u00e9but, refuse de collaborer. Mais, par la suite, il le remplit de son c\u00f4t\u00e9 avec une version diff\u00e9rente des faits.<\/p>\n<p>Dans les deux situations, il est judicieux de r\u00e9colter un maximum de preuves pour d\u00e9terminer le responsable ou la responsable:<\/p>\n<ul>\n<li>photos des deux v\u00e9hicules pour montrer les d\u00e9tails des dommages mat\u00e9riels et\/ou corporels,<\/li>\n<li>t\u00e9moignages de personnes tiers ayant assist\u00e9 \u00e0 l\u2019accident, etc.<\/li>\n<\/ul>\n<h3><strong>Accident responsable\u00a0? Sans constat amiable : comment votre assureur \u00e9tablit-il les responsabilit\u00e9s\u2009?<\/strong><\/h3>\n<p>Un automobiliste ind\u00e9licat a percut\u00e9 votre <strong>v\u00e9hicule<\/strong> en stationnement. Il est parti sans laisser une possibilit\u00e9 de le contacter, il a commis un <strong>d\u00e9lit de fuite<\/strong>. Dans cette situation, si vous avez souscrit <strong>la garantie tous risques<\/strong>, vous pouvez percevoir une indemnisation, et ce, en fonction des conditions mentionn\u00e9es dans votre contrat d&rsquo;<strong>assurance auto<\/strong>. Si vous voulez mettre \u00e0 jour votre assurance, n\u2019h\u00e9sitez pas \u00e0 effectuer un devis en ligne pour en savoir plus. Toutes les modalit\u00e9s seront affich\u00e9es sur le devis.<\/p>\n<p>Faute de<strong> description officielle<\/strong> valide ou de t\u00e9moins, cela d\u00e9pend des circonstances, l<strong>a compagnie d\u2019assurance<\/strong> peut opter pour un partage des responsabilit\u00e9s \u00e0 parts \u00e9gales : 50\/50. Si la d\u00e9claration n\u2019est pas bien remplie et\/ou non sign\u00e9e amiablement par vous et la personne adverse. Dans ce cas, il peut y avoir une application d\u2019un malus ou d\u2019un demi-malus.<\/p>\n<p>En trouvant des t\u00e9moins sur place, pr\u00eats \u00e0 fournir leur version des faits \u00e0 votre <strong>assureur<\/strong>, vous pouvez esp\u00e9rer un partage de la responsabilit\u00e9 plus juste, m\u00eame en cas d\u2019accrochage <strong>sans constat<\/strong>.<\/p>\n<h3><strong>\u00cates-vous couvert par votre assureur si vous pr\u00eatez votre voiture \u00e0 quelqu\u2019un\u00a0?<\/strong><\/h3>\n<p>Lors d\u2019un pr\u00eat de v\u00e9hicule, vous pouvez \u00eatre couvert par la compagnie d\u2019assurance. Seulement, le pr\u00eat doit figurer comme autoris\u00e9 dans votre contrat. Dans le cas contraire, vous percevrez une indemnisation limit\u00e9e et la franchise appliqu\u00e9e pourra \u00eatre major\u00e9e.<\/p>\n<h3><strong>Accident sans constat \u00e0 cause d\u2019un d\u00e9lit fuite : que dit la loi\u2009?<\/strong><\/h3>\n<p>En cas de <strong>d\u00e9lit de fuite<\/strong>, le <strong>conducteur <\/strong>de l\u2019autre parti n\u2019a pas assur\u00e9 la s\u00e9curit\u00e9 de chacun. Il s\u2019expose donc \u00e0 :<\/p>\n<ul>\n<li>une peine de prison pouvant aller jusqu\u2019\u00e0 trois ans\u2009;<\/li>\n<li>une suspension de permis\u2009;<\/li>\n<li>une amende de 75\u2009000 \u20ac, selon l\u2019Article L231-1 du Code de la route.<\/li>\n<\/ul>\n<p>Si identifi\u00e9, il endosse \u00e9galement tous les torts de l\u2019<strong>accrochage que vous soyez victime ou responsable<\/strong>.<\/p>\n<p>Il faut savoir que l\u2019\u00e9vasion de l\u2019autre partie ne peut \u00eatre retenue que si le <strong>conducteur<\/strong> ne s\u2019est pas arr\u00eat\u00e9. En effet, dans le cas o\u00f9 il manifestait un arr\u00eat, m\u00eame juste le temps suffisant pour enregistrer sa <strong>plaque immatriculation<\/strong> du v\u00e9hicule, la jurisprudence d\u00e9clare qu\u2019il n\u2019y a pas de <strong>d\u00e9lit de fuite<\/strong>.<\/p>\n<p>La <strong>panique <\/strong>de l\u2019autre <strong>conducteur <\/strong>ne doit pas vous emp\u00eacher de <strong>r\u00e9diger un constat amiable<\/strong>, en indiquant tous les \u00e9l\u00e9ments en votre possession.<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A lire aussi:<\/strong><\/p>\n<ul>\n<li>Tout savoir sur le constat d\u2019assurance auto (PDF)<\/li>\n<li>Assurance automobile : Refus de constat amiable, que faire ?<\/li>\n<li>1er accident responsable malus : ce qu\u2019il faut conna\u00eetre<\/li>\n<li>Tout savoir sur un accident non responsable<\/li>\n<li>Accident responsable : malus auto et cons\u00e9quences sur votre assurance<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Accident sans constat : quelles sont les origines et comment proc\u00e9der\u2009? D\u00e9clarer un accident de voiture n\u2019est pas une obligation. Mais m\u00eame si vous \u00eates la victime, en cas d\u2019accident o\u00f9 il n\u2019y a pas de constat, votre assureur est dans l\u2019impossibilit\u00e9 de vous rembourser les dommages. En effet, c\u2019est une d\u00e9marche quasi-obligatoire par [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Accident sans constat : pourquoi et comment proc\u00e9der\u2009? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Accident sans constat, que risquez-vous ? Comment proc\u00e9der pour \u00eatre indemnis\u00e9 avec son assurance ? Voici tous les sc\u00e9narios possibles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Accident sans constat : pourquoi et comment proc\u00e9der\u2009? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Accident sans constat, que risquez-vous ? Comment proc\u00e9der pour \u00eatre indemnis\u00e9 avec son assurance ? Voici tous les sc\u00e9narios possibles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-26T04:01:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"7 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/\",\"name\":\"Accident sans constat : pourquoi et comment proc\\u00e9der\\u2009? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-08-26T04:01:06+00:00\",\"dateModified\":\"2025-07-07T14:02:18+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Accident sans constat, que risquez-vous ? Comment proc\\u00e9der pour \\u00eatre indemnis\\u00e9 avec son assurance ? Voici tous les sc\\u00e9narios possibles.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-sans-constat-pourquoi-et-comment-proceder\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3256"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3256"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3256\/revisions"}],"predecessor-version":[{"id":3576,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3256\/revisions\/3576"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3256"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}