{"id":3258,"date":"2022-09-13T06:00:52","date_gmt":"2022-09-13T04:00:52","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/"},"modified":"2025-07-07T16:02:18","modified_gmt":"2025-07-07T14:02:18","slug":"abs-moto-de-quoi-sagit-il-exactement","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/","title":{"rendered":"ABS Moto, de quoi s\u2019agit-il exactement ?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2><strong>Tout savoir sur l&rsquo;ABS moto<\/strong><\/h2>\n<p>Avez-vous d\u00e9j\u00e0 entendu parler de l\u2019<strong>ABS<\/strong> <strong>sur les<\/strong> <strong>motos ? <\/strong>Depuis quelques ann\u00e9es, l\u2019<strong>ABS <\/strong>est devenu obligatoire pour la voiture et maintenant \u00e9galement pour la moto. Ce produit reste cependant optionnel sur certaines deux roues neuves. Le <strong>syst\u00e8me ABS <\/strong>se d\u00e9finit comme <strong>un organe de<\/strong> <strong>s\u00e9curit\u00e9 m\u00e9canique <\/strong>grandement efficace et repr\u00e9sente un plus pour une assurance. Il sert d\u2019<strong>antiblocage des roues <\/strong>de la <strong>moto ou l\u2019auto <\/strong>gr\u00e2ce \u00e0 plusieurs capteurs<strong>. <\/strong>Suite \u00e0 un test de freinage<strong>, <\/strong>avec et sans ABS, il est prouv\u00e9 que ce <strong>syst\u00e8me<\/strong> <strong>d\u2019assistance <\/strong>permettait d\u2019<strong>esquiver les<\/strong> <strong>accidents mortels <\/strong>et surtout de r\u00e9duire leur gravit\u00e9. Comment fonctionne ce <strong>syst\u00e8me de s\u00e9curit\u00e9 ? <\/strong>Y a-t-il des inconv\u00e9nients \u00e0 ce syst\u00e8me ? Comment le contr\u00f4ler ? Voici quelques points \u00e0 conna\u00eetre sur le sujet.<\/p>\n<p>Notre conseil\u00a0: Si l\u2019impl\u00e9mentation de l\u2019ABS vous int\u00e9resse, n\u2019h\u00e9sitez pas \u00e0 contacter votre courtier d\u2019assurance pour connaitre les effets sur votre formule d\u2019assurance.<\/p>\n<h3><strong>Qu\u2019est-ce que le syst\u00e8me ABS ?<\/strong><\/h3>\n<p>Provenant d\u2019Allemagne, l\u2019<strong>ABS <\/strong>ou Antiblockiersystem est issu de l\u2019auto. Ce <strong>syst\u00e8me m\u00e9canique \u00e9vite aux roues de se bloquer<\/strong> au moment du <strong>freinage gr\u00e2ce \u00e0 plusieurs capteurs. <\/strong>Il est arriv\u00e9 sur les motos vers la fin des ann\u00e9es 80, gr\u00e2ce \u00e0 la s\u00e9rie K de BMW<strong>, <\/strong>avant de se g\u00e9n\u00e9raliser chez les autres marques comme honda, ducati, kawasaki, yamaha, advenure et m\u00eame harley davidson.<\/p>\n<h4><strong>Le fonctionnement de ce syst\u00e8me ABS<\/strong><\/h4>\n<p><strong>Le syst\u00e8me antiblocage <\/strong>se compose de capteurs de rotation install\u00e9s sur chaque roue. Il est \u00e9galement dot\u00e9 d\u2019un calculateur et d\u2019une centrale hydraulique intervenant sur <strong>la pression du liquide de<\/strong> <strong>frein. <\/strong>Lorsque le motard freine, le calculateur enregistre la vitesse des deux roues. Au cas o\u00f9 une roue s\u2019arr\u00eaterait de tourner, la centrale rel\u00e2che aussit\u00f4t la pression. La roue se remettra ainsi en rotation pour retrouver toute l\u2019adh\u00e9rence disponible. Bien \u00e9videmment, ce syst\u00e8me ABS ne sera efficace que si l\u2019intervention et le calcul se font rapidement. Dans ce genre de situation, l\u2019\u00e9lectronique entre en jeu <strong>\u00e0 travers un capteur de vitesse<\/strong>.<\/p>\n<h4><strong>Le d\u00e9veloppement de l\u2019ABS moto<\/strong><\/h4>\n<p>Tous les avis s\u2019accordent pour dire que le <strong>syst\u00e8me de freinage antiblocage ABS <\/strong>continue de s\u2019am\u00e9liorer avec le temps gr\u00e2ce aux constructeurs comme Yamaha, adventure ou ktm et son duke. \u00c0 ce jour, <strong>les nouvelles g\u00e9n\u00e9rations d\u2019ABS <\/strong>sont souvent coupl\u00e9es avec un <strong>syst\u00e8me anti-patinage<\/strong>. Elles tiennent compte de l\u2019inclinaison du 2 roues.<strong>\u00a0<\/strong>Ce param\u00e8tre modifie en effet les conditions d\u2019adh\u00e9rence d\u2019une roue.<strong>\u00a0<\/strong>Entre autres, pour combiner la performance et la s\u00e9curit\u00e9, le degr\u00e9 d\u2019intervention de ce <strong>syst\u00e8me de frein ABS moderne<\/strong> <strong>peut \u00eatre param\u00e9tr\u00e9<\/strong> ou d\u00e9connect\u00e9 sur la roue arri\u00e8re.<\/p>\n<h4><strong>Le danger du syst\u00e8me antiblocage<\/strong><\/h4>\n<p>Devant une situation d\u2019urgence, le freinage reste le premier r\u00e9flexe d\u2019un motard. Le <strong>freinage d\u2019urgence<\/strong> implique la gestion d&rsquo;\u00e9ventuels blocages de roues.<strong>\u00a0<\/strong>Le <strong>syst\u00e8me antiblocage freins ABS <\/strong>fait dispara\u00eetre ce risque de blocage. Ce syst\u00e8me <strong>module la puissance du<\/strong> <strong>freinage <\/strong>\u00e0 la place du motard. M\u00eame si le freinage sans blocage ne convient pas \u00e0 un freinage plus court avec le <strong>syst\u00e8me ABS<\/strong>, le conducteur de la moto peut tout de m\u00eame <strong>\u00e9viter de chuter<\/strong>. L\u2019ABS moto permet de bloquer la roue, mais il ne modifie en aucun cas la <strong>distance freinage <\/strong>indispensable pour stopper le motard.<\/p>\n<h3><strong>Je roule sur une moto sans ABS, que faire\u00a0? <\/strong><\/h3>\n<p>Selon la cat\u00e9gorie, il est obligatoire ou non d\u2019avoir un syst\u00e8me ABS sur sa moto. S\u2019il s\u2019agit d\u2019un 125 par exemple, vous pouvez toujours l\u2019impl\u00e9menter en garage pour rester \u00e0 la page. Sinon vous pouvez commander une pi\u00e8ce parmi les produits via une livraison pour le faire vous-m\u00eame. Vous voulez votre v\u00e9hicule dans un total look noir ? Le syst\u00e8me de s\u00e9curit\u00e9 est m\u00eame personnalisable. Il est disponible, selon le stock disponible, en noir, blanc, etc. Pour plus de rapidit\u00e9, pr\u00e9f\u00e9rez une autre couleur au noir. En effet, le stock d\u2019une autre couleur peut \u00eatre plus fourni par rapport au noir.<\/p>\n<h3><strong>Mieux comprendre l\u2019ABS <\/strong><\/h3>\n<h4><strong>L\u2019ABS fonctionne dans toutes les situations <\/strong><\/h4>\n<p>Ce syst\u00e8me est pr\u00e9vu pour fonctionner dans la plupart des situations \u00e0 condition que ce soit sur du bitume. En cas de boue ou d\u2019une route de terre lors d\u2019un touring ou du camping par exemple, ce sera inop\u00e9rant et vous risquez la chute.<\/p>\n<h4><strong>La distance de freinage est diminu\u00e9e compar\u00e9 \u00e0 d\u2019autres syst\u00e8mes<\/strong><\/h4>\n<p>Non, le syst\u00e8me est con\u00e7u pour augmenter l\u2019adh\u00e9rence avec la surface et \u00e9viter toute chute. Cela ne signifie pas que la distance est raccourcie. Cependant, la sensation de freinage peut-\u00eatre renforc\u00e9 selon le TCS (Traction control system).<\/p>\n<h4><strong>Le TCS et la bpa recommandent ce syst\u00e8me<\/strong>.<\/h4>\n<p>Apr\u00e8s une s\u00e9rie de test men\u00e9e par le TCS, les capteurs n\u2019interf\u00e8rent ni la sensibilit\u00e9 des freins, ni le plaisir de conduite selon le TCS et le bpa (Bureau de pr\u00e9vention des accidents). Le plaisir de conduit est peut \u00eatre subjectif suite au test. Toutefois, l\u2019avis du TCS et du bpa demeurent positif et ils recommandent donc vivement l\u2019achat neuf ou d\u2019occasion de v\u00e9hicules avec assistance.<\/p>\n<h3><strong>L\u2019ABS est-il pr\u00e9sent chez toutes les marques\u00a0? <\/strong><\/h3>\n<p>Oui, <strong>l\u2019Union europ\u00e9enne a impos\u00e9 le<\/strong> <strong>syst\u00e8me ABS sur toutes les<\/strong> <strong>motos<\/strong> de plus de 125 centim\u00e8tres cubes depuis 2017. Pour les deux roues<strong>, <\/strong>dont le poids fait entre 50 et 125 cm<sup>3<\/sup>, le syst\u00e8me est remplac\u00e9 par un <strong>freinage combin\u00e9<\/strong>. Il n\u2019est d\u2019ailleurs plus possible d\u2019acheter des v\u00e9hicules encore en stock sans ce syst\u00e8me et appartenant \u00e0 ces cat\u00e9gories. Par ailleurs, la pr\u00e9sence d\u2019ABS peut parfois augmenter la vitesse de fabrication. Attention au stock du mod\u00e8le (ktm duke, ducati cbr, etc.) que vous voulez acheter. Il est clair que la livraison d\u2019un mod\u00e8le diff\u00e8re d\u2019un mod\u00e8le \u00e0 l&rsquo;autre.<\/p>\n<p>Sachez \u00e9galement que si vous voulez louer une moto pour du camping ou du touring, les v\u00e9hicules de location auront dans la plupart des cas le syst\u00e8me ABS int\u00e9gr\u00e9. Puisque <strong>la pr\u00e9sence d\u2019ABS est un bonus pour l\u2019assurance<\/strong> gr\u00e2ce \u00e0 la pr\u00e9sence de capteur, alors vous n\u2019y manquerez pas. Attention cependant dans un camping ou touring. Comme dit plus haut, <strong>l\u2019ABS ne vous aidera pas sur des routes de terre, la neige ou la boue.<\/strong><\/p>\n<p>Chaque constructeur participe \u00e0 l\u2019\u00e9volution de ce syst\u00e8me en plus de l\u2019innovation faite pour la voiture et donc, pour rester \u00e0 la page, chaque marque a sa technologie avec ses sp\u00e9cificit\u00e9s.<\/p>\n<p>Honda, leader de march\u00e9, a commenc\u00e9 ses travaux sur l\u2019ABS d\u00e8s les ann\u00e9es 70. \u00a0Depuis 2010, Honda s\u2019est engag\u00e9 \u00e0 homologuer leur moto d\u2019un syst\u00e8me CBS ou CBS-ABS. C\u2019est le cas pour la Honda CBR par exemple.<\/p>\n<p>Bosch a re\u00e7u le Prix \u00ab\u00a0Gelber Engel\u00a0\u00bb pour l\u2019\u00e9laboration de son dernier syst\u00e8me antiblocage en 2010. Toutes les cat\u00e9gories de moto peuvent \u00eatre \u00e9quip\u00e9es du syst\u00e8me Bosch.<\/p>\n<p>A noter que d\u2019autres marques ont leur propre syst\u00e8me. C\u2019est le cas de BMW tout comme Ducati, Suzuki ou Kawasaki. Harley Davidson propose, quant \u00e0 elle, un ensemble complet compos\u00e9 du syst\u00e8me ABS, TCS et DSCS sur les nouveaux mod\u00e8les de leur mythique Harley.<\/p>\n<p>Finalement, peu importe la marque que vous choisissez, devant se mettre \u00e0 la page, cette technologie est disponible pour les mod\u00e8les de chaque constructeur\u00a0:<\/p>\n<ul>\n<li>Honda (CBR, etc.)<\/li>\n<li>BMW<\/li>\n<li>Yamaha<\/li>\n<li>Kawasaki<\/li>\n<li>Suzuki<\/li>\n<li>Ducati<\/li>\n<li>Harley Davidson<\/li>\n<li>Bosch<\/li>\n<li>Adventure<\/li>\n<li>ktm (notamment la duke), etc.<\/li>\n<\/ul>\n<h3><strong>Comment contr\u00f4ler le freinage ABS moto ?<\/strong><\/h3>\n<p>Un <strong>syst\u00e8me d&rsquo;antiblocage offre un surplus de s\u00e9r\u00e9nit\u00e9<\/strong>. Mais vous ne devez pas minimiser les <strong>v\u00e9rifications r\u00e9guli\u00e8res de vos<\/strong> <strong>freins. <\/strong>Vous pouvez aussi proc\u00e9der \u00e0 une partie de leur entretien usuel, sans passer par un sp\u00e9cialiste. Sur chaque extr\u00e9mit\u00e9, un ABS moto (ktm duke par exemple) est similaire \u00e0 un freinage classique. Les points de contr\u00f4les courants demeurent donc primordiaux. Il s\u2019agit d\u2019effectuer un test \u00e0 la fois l\u2019\u00e9tat du ma\u00eetre-cylindre, la stabilisation de l\u2019\u00e9trier, la d\u00e9gradation des plaquettes de frein ainsi que le niveau et l\u2019\u00e9tat du fluide.<\/p>\n<h4><strong>Les caract\u00e9ristiques du syst\u00e8me ABS<\/strong><\/h4>\n<p>Pour bien utiliser votre <strong>syst\u00e8me ABS moto sur votre adventure, votre ducati ou autres, <\/strong>vous devez apprendre par c\u0153ur \u00e0 interpr\u00e9ter les signaux renvoy\u00e9s par le voyant <strong>ABS gr\u00e2ce au capteur<\/strong>. Ce dernier peut en effet clignoter, mais il peut \u00e9galement rester allum\u00e9 en roulant. Ces signaux peuvent vous \u00e9viter d\u2019angoisser en conduisant. Ils vous indiquent \u00e9galement l\u2019<strong>origine d\u2019un probl\u00e8me<\/strong>. Vous devez donc <strong>prendre soin de regarder les \u00e9metteurs de rotation des<\/strong> <strong>roues <\/strong>qui sont souvent fortement expos\u00e9s. Veillez \u00e9galement \u00e0 m\u00e9nager ces \u00e9metteurs du d\u00e9capage agressif des nettoyeurs \u00e0 haute pression.<\/p>\n<h4><strong>Le r\u00f4le des plaquettes sur le syst\u00e8me ABS<\/strong><\/h4>\n<p>L\u2019intervention judicieuse du <strong>syst\u00e8me antiblocage ABS moto <\/strong>subit une <strong>augmentation <\/strong>suivant le comportement des plaquettes de <strong>frein<\/strong> <strong>d\u2019origine. <\/strong>Vous devez avantager les pi\u00e8ces originales de votre moto lorsque vous les remplacez, sauf recommandation explicite d\u2019un m\u00e9canicien professionnel. De plus, elles combinent en g\u00e9n\u00e9ral une tr\u00e8s bonne endurance, <strong>une efficacit\u00e9 optimale et un prix abordable<\/strong>.<\/p>\n<h4><strong>La n\u00e9cessit\u00e9 de la purge<\/strong><\/h4>\n<p>Comme la centrale ABS demeure complexe pour tous les v\u00e9hicules (yamaha, suzuki, etc.), cela implique d\u2019utiliser une machine de purge. Celle-ci <strong>permet de remplacer enti\u00e8rement l\u2019ancien liquide<\/strong> sans pour autant laisser <strong>des bulles d\u2019air s\u2019introduire dans le<\/strong> <strong>syst\u00e8me. <\/strong>Pour le freinage, <strong>ces bulles d\u2019air sont catastrophiques<\/strong>. Cependant, si vous voulez vous charger vous-m\u00eame du d\u00e9pannage de votre moto<strong>, <\/strong>vous pouvez rafra\u00eechir les \u00e9triers en chassant une quantit\u00e9 suffisante de liquide souill\u00e9 \u00e0 travers la vis de purge.<\/p>\n<p><em>Selon l\u2019\u00e9valuation subjective des pilotes d\u2019essai, le syst\u00e8me ABS n\u2019affecte pas la joie de la conduite et encore moins la sensibilit\u00e9 des freins.<strong>\u00a0<\/strong>Lorsque vous r\u00e9alisez \u00e0 un freinage \u00e0 fond avec <strong>l\u2019ABS moto, <\/strong>la pulsion du levier de <strong>freinage <\/strong>s\u2019active. Cette r\u00e9action encourage <strong>votre confiance et<\/strong> <strong>assurance<\/strong> <strong>dans les<\/strong> <strong>freins <\/strong>et vous vous sentez en <strong>s\u00e9curit\u00e9 sans blocage des roues. <\/strong>Si l\u2019on part de ces impressions subjectives et de ces mesures objectives, le <strong>TCS BPA recommande <\/strong>vivement l\u2019acquisition de <strong>motos \u00e9quip\u00e9es ABS<\/strong> neuves ou d\u2019occasion.<\/em><\/p>\n<p>[\/vc_column_text][\/vc_column][vc_column][vc_row_inner el_class=\u00a0\u00bbsgnx-delete-onimport\u00a0\u00bb][vc_column_inner][sgnx_spacer spacer_size=\u00a0\u00bbsgnx-spacer&#8211;sm\u00a0\u00bb][vc_column_text]<\/p>\n<p><strong>A lire aussi :<\/strong><\/p>\n<ul>\n<li>Choisir la meilleure assurance moto et ses garanties<\/li>\n<li>Assurance pour moto : combien de personnes dans un contrat ?<\/li>\n<li>Conseils assurance moto : rouler en groupe \u00e0 moto<\/li>\n<li>Assurance moto : \u00eatre un bon passager \u00e0 moto<\/li>\n<li>combinaison pluie moto et \u00e9quipements\u2026<\/li>\n<li>Comment faire sa demande de carte grise moto ?<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Tout savoir sur l&rsquo;ABS moto Avez-vous d\u00e9j\u00e0 entendu parler de l\u2019ABS sur les motos ? Depuis quelques ann\u00e9es, l\u2019ABS est devenu obligatoire pour la voiture et maintenant \u00e9galement pour la moto. Ce produit reste cependant optionnel sur certaines deux roues neuves. Le syst\u00e8me ABS se d\u00e9finit comme un organe de s\u00e9curit\u00e9 m\u00e9canique grandement efficace [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>ABS Moto, de quoi s\u2019agit-il exactement ? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"ABS Moto : toutes les sp\u00e9cificit\u00e9s du syst\u00e8me de freinage obligatoire sur son fonctionnement, ses avantages et ses d\u00e9savantages.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ABS Moto, de quoi s\u2019agit-il exactement ? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"ABS Moto : toutes les sp\u00e9cificit\u00e9s du syst\u00e8me de freinage obligatoire sur son fonctionnement, ses avantages et ses d\u00e9savantages.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-13T04:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"9 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/\",\"name\":\"ABS Moto, de quoi s\\u2019agit-il exactement ? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-09-13T04:00:52+00:00\",\"dateModified\":\"2025-07-07T14:02:18+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"ABS Moto : toutes les sp\\u00e9cificit\\u00e9s du syst\\u00e8me de freinage obligatoire sur son fonctionnement, ses avantages et ses d\\u00e9savantages.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/abs-moto-de-quoi-sagit-il-exactement\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3258"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3258"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3258\/revisions"}],"predecessor-version":[{"id":3577,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3258\/revisions\/3577"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3258"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3258"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}