{"id":3266,"date":"2022-09-23T04:50:50","date_gmt":"2022-09-23T02:50:50","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-au-tiers-et-accident-responsable\/"},"modified":"2025-07-07T16:02:18","modified_gmt":"2025-07-07T14:02:18","slug":"assurance-au-tiers-et-accident-responsable","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-au-tiers-et-accident-responsable\/","title":{"rendered":"Assurance au tiers et accident responsable"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2><strong>Assurance au tiers et accident responsable : on vous explique tout<\/strong><\/h2>\n<p>Tous les conducteurs poss\u00e9dant un v\u00e9hicule \u00e0 moteur (auto, moto, scooter\u2026) se doit de <u>souscrire une <strong>assurance auto<\/strong><\/u> pour se couvrir en cas de <strong>sinistre ou d\u2019accident de la route. <\/strong>Vous recherchez une bonne <strong>assurance<\/strong> <strong>auto <\/strong>tout en b\u00e9n\u00e9ficiant d\u2019une couverture au meilleur prix ? L\u2019<strong>assurance au tiers <\/strong>reste la <strong>formule minimale obligatoire<\/strong> en France. Cette derni\u00e8re est<strong> accessible \u00e0 un prix raisonnable<\/strong>. Elle est utile pour circuler sur la voie publique, et m\u00eame lorsque votre <strong>voiture <\/strong>reste au garage. Quels sont les avantages de l&rsquo;<strong>assurance au tiers en cas d\u2019accident responsable ?<\/strong> Que concerne-t-elle exactement ? \u00c0 qui profite l\u2019assurance auto au\u00a0tiers ? Quels sont les risques couverts par cette garantie ? Qu\u2019en est-il de votre bonus-malus\u00a0? Les quelques points suivants peuvent vous \u00e9clairer \u00e0 ce sujet.<\/p>\n<h3><strong>Assurance auto au tiers : c\u2019est quoi ?<\/strong><\/h3>\n<p>Selon l\u2019<u>article L211-4 du Code des <strong>assurances<\/strong><\/u><strong>, <\/strong>pour circuler, n\u2019importe quel propri\u00e9taire de v\u00e9hicule doit \u00eatre au moins couvert par une <strong>assurance responsabilit\u00e9 civile. <\/strong>Il semble donc impossible de rouler sans assurance, en vue des risques et des sanctions encourus notamment en cas d\u2019accidents.<\/p>\n<h4><strong>D\u00e9finition<\/strong><\/h4>\n<p><u>L\u2019<strong>assurance au tiers<\/strong><\/u> pour une voiture ou tout autre v\u00e9hicule correspond au niveau de <strong>garantie minimum<\/strong>. Il s\u2019agit de la <strong>formule la moins co\u00fbteuse<\/strong> propos\u00e9e par les compagnies d\u2019assurance.<strong> Elle couvre le minimum en termes de risques. <\/strong>Elle r\u00e9pond exclusivement \u00e0 des exigences l\u00e9gales. Cela signifie qu\u2019en cas de proc\u00e8s, les assureurs y incluent la <strong>responsabilit\u00e9 civile <\/strong>et une protection juridique. Si l\u2019assur\u00e9 souhaite obtenir plus de garanties, il devrait souscrire \u00e0 une <strong>assurance au tiers <\/strong>\u00e9tendu ou \u00e0 une <u><strong>assurance auto <\/strong>tous risques<\/u>. L\u2019assurance au tiers \u00e9tendu est une formule de gamme moyenne. Ces deux types de couvertures garantissent les v\u00e9hicules en cas de sinistres multiples, comme pendant un incendie, un vol, une catastrophe naturelle ou tous autres dommages \u00e9ventuels. Par rapport aux autres formules, l\u2019<strong>assurance au tiers responsabilit\u00e9 civile <\/strong>demeure plus \u00e9conomique.<\/p>\n<h4><strong>Les tiers, juridiquement parlant<\/strong><\/h4>\n<p>Aux yeux de la loi, le terme tiers d\u00e9signe tout individu autre que le chauffeur du v\u00e9hicule terrestre \u00e0 moteur concern\u00e9 dans l\u2019<strong>accident de la route. <\/strong>Lorsque l\u2019on parle d\u2019un tiers il peut donc s\u2019agir :<\/p>\n<ul>\n<li>Du <strong>conducteur <\/strong>de l\u2019autre <strong>v\u00e9hicule, avec lequel votre v\u00e9hicule entre en collision,<\/strong> et de ses passagers ;<\/li>\n<li>Du ou des passagers de votre voiture <strong>;<\/strong><\/li>\n<li>D\u2019un pi\u00e9ton ;<\/li>\n<li>D\u2019un cycliste ;<\/li>\n<li>De l\u2019individu qui occupe un v\u00e9hicule en stationnement ;<\/li>\n<li>De l\u2019occupant d\u2019une r\u00e9sidence ou d\u2019un local commercial avec lequel votre <strong>v\u00e9hicule <\/strong>entre en collision.<\/li>\n<\/ul>\n<p>Bref, les tiers concernent toutes les personnes physiques, c\u2019est-\u00e0-dire les victimes de l\u2019<strong>accident de la route <\/strong>que vous avez caus\u00e9, ainsi que leurs biens mat\u00e9riels et immat\u00e9riels ayant subis des dommages.<\/p>\n<h3><strong>Accident responsable : comment fonctionne l\u2019assurance tiers ?<\/strong><\/h3>\n<p>Comme l\u2019assurance au tiers reste la <strong>formule proposant une garantie minimale<\/strong>, le <strong>conducteur <\/strong>assur\u00e9 ne per\u00e7oit pas d\u2019<strong>indemnisation <u>en cas d\u2019accident responsable.<\/u><\/strong> Ni pour son v\u00e9hicule (par exemple : pour les r\u00e9parations) ou ni pour sa personne,. En effet, le <strong>tiers en assurance<\/strong> ne propose pas d\u2019indemnisation dans ce cas, car elle ne prend pas en charge les \u00e9ventuels <strong>dommages<\/strong> <strong>physiques<\/strong> <strong>subis<\/strong>, par l\u2019assur\u00e9, lors de l\u2019accident<strong> de voiture<\/strong>.<\/p>\n<h4><strong>Le r\u00f4le de la garantie responsabilit\u00e9 civile<\/strong><\/h4>\n<p>La <strong>garantie responsabilit\u00e9 civile <\/strong>du <strong>conducteur responsable de l\u2019accident de voiture <\/strong>a pour objectif l\u2019<strong>indemnisation<\/strong> <strong>des victimes<\/strong> pour les pr\u00e9judices qu\u2019elles ont endur\u00e9s, \u00e0 savoir : les <strong>dommages<\/strong> <strong>corporels<\/strong>, tout comme <strong>les dommages mat\u00e9riels et immat\u00e9riels<\/strong>. Dans ce genre de situation, la personne ayant subi ces dommages ne peut pas \u00eatre impos\u00e9e de<strong> franchise<\/strong> (montant qui reste \u00e0 sa charge apr\u00e8s l&rsquo;indemnisation de l&rsquo;assureur).<\/p>\n<h4><strong>La possibilit\u00e9 de prestations en option<\/strong><\/h4>\n<p>La plupart des <strong>contrats <\/strong>d\u2019<strong>assurance auto au tiers <\/strong>pr\u00e9voient des services optionnels en plus de la responsabilit\u00e9 civile. Il peut s\u2019agir :<\/p>\n<ul>\n<li>Du service d\u2019<u>assistance remorquage<\/u> en cas de collision ;<\/li>\n<li>Du rapatriement du v\u00e9hicule en <u>cas de panne<\/u> ou d\u2019<strong>accident responsable ou non ;<\/strong><\/li>\n<li>De l\u2019emprunt d\u2019un v\u00e9hicule de remplacement, le temps d\u2019effectuer les diverses r\u00e9parations.<\/li>\n<\/ul>\n<p>Vous devez n\u00e9anmoins savoir que chaque <strong>accident responsable fera augmenter votre malus<\/strong> d\u2019assurance <strong>de 25 %.<\/strong> Cette hausse s\u2019applique, <strong>peu importe la gravit\u00e9 du<\/strong> <strong>sinistre<\/strong> <strong>auto. <\/strong>Votre assureur a \u00e9galement la possibilit\u00e9 de d\u00e9cider sur l\u2019application ou non d\u2019une prime, d\u2019une surprime ou d\u2019une majoration de votre cotisation en fonction des circonstances et des causes de l\u2019accident, celles-ci rapport\u00e9es dans un constat.<\/p>\n<h4><strong>Le cas d\u2019accident de voiture non responsable<\/strong><\/h4>\n<p>Lorsque vous \u00eates li\u00e9s \u00e0 un <strong>accident auto, moto ou autre (sur la route, en stationnement, etc\u2026) ou un sinistre <\/strong>et que celui-ci <strong>d\u00e9pend de la<\/strong> <strong>responsabilit\u00e9 d\u2019un<\/strong> <strong>tiers, <\/strong>vous recevez un certain montant d\u2019<strong>indemnisation de la part de votre<\/strong> <strong>assureur <\/strong>de la personne responsable. Le montant de votre indemnisation sera calcul\u00e9 \u00e0 partir des diff\u00e9rents <strong>dommages corporels ou d\u00e9g\u00e2ts mat\u00e9riels <\/strong>que vous avez subis (bris de glace, jambe cass\u00e9e ou autre\u2026). Dans ce cas, en tant que <strong>chauffeur<\/strong> <strong>non responsable<\/strong>, vous ne supporterez aucune franchise sur votre contrat d\u2019assurance auto. En effet, votre compagnie d&rsquo;assurance vous indemnise et aucun malus ou prime ne vous sera non plus appliqu\u00e9.<\/p>\n<h3><strong>Assurance tiers : quelles sont les garanties facultatives ?<\/strong><\/h3>\n<p>Puisque les garanties de l\u2019assurance au tiers semblent limit\u00e9es, la plupart des conducteurs assur\u00e9s pr\u00e9f\u00e8rent <strong>souscrire \u00e0 un contrat d\u2019assurance <\/strong>avec des <strong>garanties optionnelles<\/strong>. Toute une vari\u00e9t\u00e9 d\u2019options reste disponible pour <strong>couvrir les<\/strong> <strong>conducteurs et leurs v\u00e9hicules. <\/strong>Les garanties en option proposent<strong> une couverture en cas de sinistre pour diff\u00e9rents d\u00e9g\u00e2ts (corporels, mat\u00e9riels), sur la route. <\/strong>Les garanties <u>bris de glace<\/u>, <u>vol<\/u> et incendie restent les plus habituelles. Vous pouvez aussi opter pour la garantie tous accidents,<strong>\u00a0<\/strong>valeur \u00e0 neuf, vandalisme, temp\u00eate, la <strong>garantie conducteur, <\/strong>celle de protection juridique ou <strong>d\u00e9fense p\u00e9nale, <\/strong>celle de l\u2019assistance, <strong>la garantie<\/strong> <strong>conducteur secondaire<\/strong>, etc.<\/p>\n<p>Au-del\u00e0 de l\u2019assurance au tiers<strong>, <\/strong>il vous est possible de <strong>choisir une assurance auto <\/strong>interm\u00e9diaire comme l\u2019<strong>assurance tiers plus ou tiers \u00e9tendu<\/strong>, etc. En g\u00e9n\u00e9ral le contrat vous couvre et vous indemnise pour diff\u00e9rentes causes\u00a0: en cas de vols, d\u00e9claration d\u2019un feu, bris de glace, et m\u00eame vandalisme. L\u2019appellation diff\u00e8re en fonction des assureurs. Il peut s\u2019agir du tiers plus, tiers \u00e9tendu, tiers confort et autre. Mais <strong>les d\u00e9marches \u00e0 suivre en cas d&rsquo;accident sont les m\u00eames<\/strong>. Vous devez <strong>r\u00e9diger un constat<\/strong> en mentionnant le <strong>type de sinistre<\/strong>, la date puis le fournir \u00e0 votre assurance pour l\u2019ajouter \u00e0 <strong>votre dossier de demande d&rsquo;indemnisation<\/strong>. De toute mani\u00e8re, si vous avez l\u2019intention de souscrire ce type d\u2019assurance tout en souhaitant avoir une meilleure couverture, vous pouvez demander \u00e0 <strong>votre expert<\/strong> <strong>assureur un devis pour la souscription de plus de garanties.<\/strong><\/p>\n<p><em>L\u2019assurance au tiers reste la formule \u00e9conomique par excellence avec la <strong>garantie responsabilit\u00e9 civile<\/strong>. Si vous \u00eates un jeune conducteur ou que vous avez un <strong>v\u00e9hicule ancien<\/strong>, elle demeure <strong>la meilleure solution<\/strong> en date pour une protection \u00e0 un prix accessible. Pour choisir le <strong>contrat<\/strong> <strong>id\u00e9al<\/strong>, une comparaison des assurances auto en r\u00e9alisant des devis et la meilleure option\u00a0! N\u2019h\u00e9sitez pas \u00e0 consulter un expert pour avoir une id\u00e9e sur les <strong>diff\u00e9rentes formules, la prime, le montant des bonus et des malus<\/strong>.\u00a0 Vous pouvez \u00e9galement demander un <strong><u>devis en ligne<\/u><\/strong> ou au niveau d&rsquo;une agence physique.<\/em><\/p>\n<p>[\/vc_column_text]<\/p>\n<p>&nbsp;<\/p>\n<p><strong>A lire aussi:<\/strong><\/p>\n<ul>\n<li>1er accident responsable malus ce qu&rsquo;il faut connaitre<\/li>\n<li>Accrochage voiture : obligations et responsabilit\u00e9s<\/li>\n<li>Tout savoir sur un accident non responsable<\/li>\n<li>Accident responsable : malus auto et cons\u00e9quences sur votre assurance<\/li>\n<\/ul>\n<p>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Assurance au tiers et accident responsable : on vous explique tout Tous les conducteurs poss\u00e9dant un v\u00e9hicule \u00e0 moteur (auto, moto, scooter\u2026) se doit de souscrire une assurance auto pour se couvrir en cas de sinistre ou d\u2019accident de la route. Vous recherchez une bonne assurance auto tout en b\u00e9n\u00e9ficiant d\u2019une couverture au meilleur [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assurance au tiers et accident responsable - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Vous souhaitez connaitre le fonctionnement d&#039;une assurance au tiers en cas d&#039;accident responsable ? NetVox vous explique tout !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurance au tiers et accident responsable - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Vous souhaitez connaitre le fonctionnement d&#039;une assurance au tiers en cas d&#039;accident responsable ? NetVox vous explique tout !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-23T02:50:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"7 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/\",\"name\":\"Assurance au tiers et accident responsable - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-09-23T02:50:50+00:00\",\"dateModified\":\"2025-07-07T14:02:18+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Vous souhaitez connaitre le fonctionnement d'une assurance au tiers en cas d'accident responsable ? NetVox vous explique tout !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-au-tiers-et-accident-responsable\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3266"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3266"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3266\/revisions"}],"predecessor-version":[{"id":3581,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3266\/revisions\/3581"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3266"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}