{"id":3284,"date":"2022-10-25T05:32:19","date_gmt":"2022-10-25T03:32:19","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/quel-modele-de-moto-choisir-en-2022\/"},"modified":"2025-07-07T16:02:19","modified_gmt":"2025-07-07T14:02:19","slug":"quel-modele-de-moto-choisir-en-2022","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/quel-modele-de-moto-choisir-en-2022\/","title":{"rendered":"Quel mod\u00e8le de moto choisir en 2022 ?"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2>Guide des mod\u00e8les de motos 2022<\/h2>\n<p>Chaque ann\u00e9e, la majorit\u00e9 des marques de fabricants de motos tels que Triumph, Harley-Davidson, Honda ou Ducati Motor connue pour sa gamme Multistrada (Multistrada V4, la Multistrada V4S ou la Multistrada V4 Sport) revoit leur gamme (Sport, Adventure, Twin, Africa etc). Ils ajoutent un modele de moto, modifient quelques d\u00e9tails et sp\u00e9cifications ou retirent une gamme disponible. Mais certains mod\u00e8les r\u00e9apparaissent de temps en temps avec quelques modifications pour laisser une impression de nouveau. M\u00eame s\u2019il n\u2019existe pas de classification officielle des diff\u00e9rentes motos, nous pouvons classer les divers mod\u00e8les de motos dans diff\u00e9rentes cat\u00e9gories. Alors, nous pouvons classer ces motos : les routi\u00e8res, les sportives, les cruisers, les roadsters, les motos tout-terrain et les duals sports (ou moto double usage). Cette cat\u00e9gorisation n\u2019est qu\u2019\u00e0 titre indicatif, notez qu\u2019un modele de moto peut faire partie de plusieurs cat\u00e9gories.<\/p>\n<p>Voici, pour les motards, le guide des nouvelles motos de derni\u00e8re g\u00e9n\u00e9ration sorties sur le march\u00e9 en 2022, avec leurs sp\u00e9cifications.<\/p>\n<p>Ainsi, on distingue<strong> 6 cat\u00e9gories moto <\/strong>en fonction de leur puissance :<\/p>\n<ul>\n<li>Cat\u00e9gorie A : Motos de plus de 50 cc et jusqu&rsquo;\u00e0 et aussi de plus de 150 cc (avec un maximum de 4 cylindres)<\/li>\n<li>Cat\u00e9gorie B : Motos entre 35 cc et 50 cc et avec moins de 150 cc (avec un maximum de 4 cylindres)<\/li>\n<li>Cat. C : Motos entre 35 cc et 50 cc et avec moins de 150 cc (avec u maximum de 2 cylindres)<\/li>\n<li>Cat. D : Motos entre 5 cc et 35 cc et avec moins de 50 cc (avec un maximum de 2 cylindres)<\/li>\n<li>E : Motos de moins de 5 cc et jusqu&rsquo;\u00e0 20 cc (avec un maximum de 2 cylindres)<\/li>\n<li>F : Motos de plus de 50 cc et jusqu&rsquo;\u00e0 150 cc (avec un maximum de 2 cylindres)<\/li>\n<\/ul>\n<p>Une fois votre choix de puissance fait, n\u2019h\u00e9sitez pas \u00e0 demander l&rsquo;avis d&rsquo;un expert afin de d\u00e9terminer parmi les assurances pour scooters, engins \u00e9lectriques, peu importe la cat\u00e9gorie (roadster, tout terrain, etc) et les sp\u00e9cifications (puissance, cylindr\u00e9e, vitesse, etc) la meilleure assurance pour votre nouveau v\u00e9hicule.<\/p>\n<h2>Choix de sa moto : Les diff\u00e9rents types de moto pour d\u00e9butant<\/h2>\n<p>Quand on d\u00e9bute dans cette discipline, il est n\u00e9cessaire de s\u2019int\u00e9resser \u00e0 chaque type de motocycle disponible et de d\u00e9couvrir les sp\u00e9cifications des diff\u00e9rentes motos (\u00e9lectriques ou thermiques) : roadster, sport, etc. Place donc aux diff\u00e9rents types de moto qui permettent de se lancer dans la pratique du motocyclisme !<\/p>\n<h3>Moto 2 roues motrices<\/h3>\n<p>La moto deux roues motrice est la plus commune sur les routes. Elle comporte une selle, le r\u00e9servoir d&rsquo;essence et des freins \u00e0 disque. Son prix est relativement abordable.<\/p>\n<h3>Moto balanc\u00e9e<\/h3>\n<p>Cette cat\u00e9gorie regroupe les motos surbaiss\u00e9es ou \u00e0 suspensions arri\u00e8re. La seule diff\u00e9rence r\u00e9side dans le fait que les c\u00e2bles qui soutiennent l&rsquo;engin \u00e0 l&rsquo;arri\u00e8re ne sont pas apparents.<\/p>\n<h3>Moto tract\u00e9es<\/h3>\n<p>Les deux roues tract\u00e9es sont tr\u00e8s similaires aux motos d&rsquo;enduro. La seule diff\u00e9rence r\u00e9side dans le fait que les c\u00e2bles qui soutiennent l&rsquo;engin \u00e0 l&rsquo;arri\u00e8re ne sont pas apparents.<\/p>\n<h3>Moto \u00e9lectrique<\/h3>\n<p>La moto \u00e9lectrique poss\u00e8de une batterie pour alimenter le moteur. Ces engins pr\u00e9sentent des sp\u00e9cifications qui font d&rsquo;eux des mod\u00e8les adapt\u00e9s aux jeunes conducteurs.<\/p>\n<h3>Moto \u00e0 trois roues<\/h3>\n<p>Cette moto est une cat\u00e9gorie de v\u00e9hicule diff\u00e9rente des autres (v\u00e9hicule ne comportant pas de selle). Ce genre d\u2019engin est utile lors des courses, car il est beaucoup plus lourd et r\u00e9sistant.<\/p>\n<h3>Moto \u00e0 quatre roues<\/h3>\n<p>Ce produit n&rsquo;est pas tr\u00e8s pr\u00e9sent sur le march\u00e9, et il se distingue des autres mod\u00e8les gr\u00e2ce \u00e0 ses roues avant et arri\u00e8re.<\/p>\n<h2>D\u00e9couvrez quelques nouveaux mod\u00e8les par marque<\/h2>\n<p>D\u00e9couvrez quelques nouveaux mod\u00e8les par marque (Yamaha, Suzuki, Kawasaki, Ducati, Triumph) disponibles dans les magasins ou nouveaux dans la cat\u00e9gorie. Cet article vous permettra d\u2019essayer des mod\u00e8les qui sont peut-\u00eatre rarement propos\u00e9s sur le march\u00e9. Ainsi, nous esp\u00e9rons vous offrir une exp\u00e9rience de mode un peu plus \u00e9largie et d\u00e9couvrir des fabricants qui ne sont pas tous connus en France.<\/p>\n<p>Vous pouvez vous rendre dans un magasin sp\u00e9cialis\u00e9 afin de tester un engin d\u00e9j\u00e0 disponible au niveau d&rsquo;une concession. Si vous aimez le style et le design du v\u00e9hicule (couleurs disponibles, finitions, etc). Une fois la d\u00e9cision prise, vous pourrez choisir une version plus haut de gamme ou plus bas de gamme (diff\u00e9rents mod\u00e8les selon la puissance, gamme de vitesse, \u00e9quipement, etc).<\/p>\n<h3>Modele 2022 Suzuki : fourche invers\u00e9e, nouvelle moto \u00e9lectrique<\/h3>\n<p>La marque Suzuki a d\u00e9voil\u00e9 plusieurs nouveaux petits bijoux. Parmi eux, il y a des v\u00e9hicules \u00e9lectriques, \u00e0 trois et quatre roues, un scooter ainsi qu\u2019une moto \u00e0 fourche invers\u00e9e.<\/p>\n<p>L&rsquo;engin \u00e0 fourche invers\u00e9e est un nouveau concept, mais qui sera bient\u00f4t propos\u00e9 sur le march\u00e9. Il s\u2019agit d\u2019un produit tendance qui peut \u00eatre utilis\u00e9 comme un engin d\u2019appartement et comme un mod\u00e8le de rue. Ce v\u00e9hicule dispose d\u2019une fourche invers\u00e9e, d\u2019un moteur \u00e9lectrique et d\u2019un freinage \u00e0 disque. \u00a0Cette nouveaut\u00e9 est con\u00e7ue pour \u00eatre plus s\u00fbre et plus simple.<\/p>\n<h3>Modele 2022 Honda : une petite moto<\/h3>\n<p>La marque japonaise Honda qui a su conqu\u00e9rir les utilisateurs par son scooter Forza 125 n&rsquo;as plus rien \u00e0 prouver. Le fabricant de la moto l\u00e9gende <strong>CRF1000L Africa Twin<\/strong> pr\u00e9sente sa petite derni\u00e8re con\u00e7ue pour les jeunes conducteurs motards. Cette Honda \u00e0 4 roues dispose d\u2019une peinture noire avec quelques touches de couleur rouge. Elle est dot\u00e9e d\u2019un moteur \u00e9lectrique et d\u2019un freinage \u00e0 disque. Toutes ses sp\u00e9cifications lui valent une place de choix parmi les mod\u00e8les \u00e9dition 2022 selon les avis des experts.<\/p>\n<p>Toutefois, les motos telles que les Forza : <strong>Forza 125<\/strong>, la <strong>NSS 350 Forza<\/strong> ou m\u00eame la <strong>Honda CRF 450 R<\/strong> et la <strong>CRF 150<\/strong> demeurent de vraies p\u00e9pites que vous pourrez admirer au niveau d&rsquo;une concession.<\/p>\n<p>Sans oublier que la soci\u00e9t\u00e9 se lance officiellement dans l&rsquo;\u00e9lectrique, notamment suite \u00e0 la cr\u00e9ation de la Joint Venture \u00ab\u00a0<strong>Sony Honda Mobility Inc.<\/strong>\u00ab\u00a0.<\/p>\n<h3>Mod\u00e8les 2022 BMW : la nouvelle Mini, la S 1000 R<\/h3>\n<p>BMW a d\u00e9voil\u00e9 plusieurs nouveaut\u00e9s tr\u00e8s attendues selon les avis des utilisateurs. Parmi celles-ci, il y a un nouveau produit tr\u00e8s appr\u00e9ci\u00e9 offrant une maniabilit\u00e9 accrue gr\u00e2ce \u00e0 son poids l\u00e9ger. La marque a \u00e9galement pr\u00e9sent\u00e9 une nouvelle Mini ainsi qu\u2019une moto sportive S 1000 R. Si vous \u00eates un grand adepte de la marque BMW, alors aller jetez un coup d&rsquo;\u0153il au petit bijou en \u00e9dition limit\u00e9 : la <strong>BMW S 1000 RR Isle of Man Edition.<\/strong><\/p>\n<h3>Mod\u00e8le 2022 Yamaha : la YZF-R1, la MT-07, la FZ-07<\/h3>\n<p>Yamaha a d\u00e9voil\u00e9 trois nouveaut\u00e9s de leurs mod\u00e8les. La premi\u00e8re en date est la <strong>YZF-R1<\/strong>. Ce v\u00e9hicule sport \u00e0 4 cylindres dispose d\u2019un freinage \u00e0 disque. Le moteur quatre cylindres en ligne de 998 cm3 est dot\u00e9 de la technologie exclusive Yamaha, d\u00e9riv\u00e9e de la moto de course <strong>YZR-M1 MotoGP<\/strong>\u00ae de la m\u00eame marque. La seconde moto est la <strong>MT-07<\/strong> m\u00e9rite largement sa place parmi les meilleurs engins roadster.<\/p>\n<p>Cet engin roadster est dot\u00e9 d\u2019un moteur de 650 cc et d\u2019un poids l\u00e9ger pour une excellente maniabilit\u00e9. Enfin, la <strong>FZ-07<\/strong> fait \u00e9galement partie des mod\u00e8les sports \u00e0 4 cylindres et d\u2019une cylindr\u00e9e de 749 cc.<\/p>\n<p>Parmi les motos sports embl\u00e9matiques et vrais chefs-d&rsquo;\u0153uvre de la marque, on retrouve la fameuse <strong>YZ 250 Monster Energy<\/strong> <strong>Edition<\/strong> dont les sp\u00e9cifications comprennent : une selle plus plate, un freinage am\u00e9lior\u00e9 gr\u00e2ce \u00e0 un nouvel \u00e9trier avant plus efficace et un disque arri\u00e8re plus l\u00e9ger,\u00a0 des suspensions recalibr\u00e9es. Elle rev\u00eat \u00e9galement une nouvelle couronne plus l\u00e9g\u00e8re. La marque est \u00e9galement salu\u00e9e pour sa gamme Scooters Urban <em>Mobility.<\/em><\/p>\n<h3>Mod\u00e8le 2022 Kawasaki : la Z900RS, la Ninja 650R, la Ninja H2 SX et la Versys 1000<\/h3>\n<p>La marque Kawasaki a pr\u00e9sent\u00e9 plusieurs mod\u00e8les de motos sportives, dont le Z900RS, la Ninja 650R, la Ninja H2 SX et la Versys 1000. La <strong>Z900RS<\/strong> est une moto sportive \u00e0 4 cylindres dot\u00e9e d\u2019un freinage \u00e0 disque et d\u2019un couple accru gr\u00e2ce \u00e0 son moteur 4 cylindres. La <strong>Ninja 650R<\/strong> est un engin sport \u00e0 4 cylindres dot\u00e9e d\u2019un freinage \u00e0 disque et d\u2019un couple accru gr\u00e2ce \u00e0 son moteur 4 cylindres. La <strong>Ninja H2 SX<\/strong> est une moto sportive \u00e0 2 cylindres. Elle dispose d\u2019un freinage \u00e0 disque et d\u2019un couple accru gr\u00e2ce \u00e0 son moteur 2 cylindres. Enfin, la <strong>Versys 1000<\/strong> est une moto sportive \u00e0 4 cylindres dot\u00e9e d\u2019un freinage \u00e0 disque et d\u2019un couple accru gr\u00e2ce \u00e0 son moteur 4 cylindres.<\/p>\n<p>Celle-ci tr\u00e8s connue pour son mod\u00e8le \u00e9legant <strong>Versys 650 \u00e9dition Mobility<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p>Pour finir, aucun de ces g\u00e9ants n&rsquo;a voulu d\u00e9cevoir ses adeptes, ils n&rsquo;ont donc pas pu ignorer le march\u00e9 de l&rsquo;aventure. Voici quelques petites perles Adventure : la <strong>BMW R 1250 GS Adventure<\/strong>, la<strong> Honda Africa Twin<\/strong>,<strong>\u00a0<\/strong>la <strong>Yamaha T<\/strong><strong>\u00e9n\u00e9r\u00e9 700.\u00a0<\/strong><\/p>\n<p>Vous pouvez \u00e9galement visiter une concession pour examiner l&rsquo;engin sur place. Vous pourrez analyser les sp\u00e9cifications de ce dernier et d\u00e9couvrir en vrai la Forza, la CRF, Multistrada de Ducati Motor et bien d&rsquo;autres encore au niveau d&rsquo;une concession.<\/p>\n<h2>En conclusion<\/h2>\n<p>Les fabricants cit\u00e9s pr\u00e9c\u00e9demment, mais \u00e9galement d&rsquo;autres marques telles que Ducati Motors, Harley-Davidson, Triumph ne cessent d&rsquo;innover en proposant des scooters, des engins tout terrain et s&rsquo;int\u00e9ressent m\u00eame \u00e0 l&rsquo;\u00e9lectrique, de quoi ravir tout le monde. Il faut ainsi r\u00e9fl\u00e9chir \u00e0 ce qu\u2019on veut et demander l&rsquo;avis d&rsquo;experts avant de s\u2019engager dans l\u2019achat d\u2019une moto ou tout autre \u00e9quipement. Une fois votre v\u00e9hicule achet\u00e9, il faut se conformer au code de la route qui est le r\u00e8glement g\u00e9n\u00e9ral des lois et des usages en France. Ce code a \u00e9t\u00e9 \u00e9tabli par les pouvoirs publics pour fixer les r\u00e8gles de conduite et de circulation sur la voie publique. Ce code est \u00e9volutif ; c\u2019est-\u00e0-dire que les modifications sont apport\u00e9es afin d\u2019am\u00e9liorer la s\u00e9curit\u00e9 des usagers de la route.<\/p>\n<p>Le code de la route comprend les articles R311-1 \u00e0 R311-7 qui portent sur l\u2019obligation d\u2019\u00eatre titulaire d\u2019un permis de conduire pour pouvoir circuler sur la voie publique ; de l\u2019article R312-1 \u00e0 R312-13 qui portent sur les cat\u00e9gories de permis et leur contenu ; de l\u2019article R313-1 \u00e0 R313-4 qui portent sur les conditions de d\u00e9livrance du permis de conduire ; et l\u2019article R314 -1 \u00e0 R314-2 qui portent sur la d\u00e9livrance du permis de conduire.<\/p>\n<p>Comme nous l&rsquo;avons signal\u00e9 \u00e0 plusieurs reprises. Il faut \u00e9galement souligner que chaque groupe disponible peut contenir de nombreux sous-groupes. Chacun jouit de sp\u00e9cifications int\u00e9ressantes (poids, couleurs, puissance, type de moteur (\u00e9lectrique, thermique, etc) prix).<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Guide des mod\u00e8les de motos 2022 Chaque ann\u00e9e, la majorit\u00e9 des marques de fabricants de motos tels que Triumph, Harley-Davidson, Honda ou Ducati Motor connue pour sa gamme Multistrada (Multistrada V4, la Multistrada V4S ou la Multistrada V4 Sport) revoit leur gamme (Sport, Adventure, Twin, Africa etc). Ils ajoutent un modele de moto, modifient [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quel mod\u00e8le de moto choisir en 2022 ? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Retrouvez les nouveaut\u00e9s motos sorties 2022. Trouvez et choisissez le modele de moto fait pour vous gr\u00e2ce \u00e0 notre guide 2022 NetVox !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quel mod\u00e8le de moto choisir en 2022 ? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Retrouvez les nouveaut\u00e9s motos sorties 2022. Trouvez et choisissez le modele de moto fait pour vous gr\u00e2ce \u00e0 notre guide 2022 NetVox !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T03:32:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"9 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/\",\"name\":\"Quel mod\\u00e8le de moto choisir en 2022 ? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-10-25T03:32:19+00:00\",\"dateModified\":\"2025-07-07T14:02:19+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Retrouvez les nouveaut\\u00e9s motos sorties 2022. Trouvez et choisissez le modele de moto fait pour vous gr\\u00e2ce \\u00e0 notre guide 2022 NetVox !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/quel-modele-de-moto-choisir-en-2022\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3284"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3284"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3284\/revisions"}],"predecessor-version":[{"id":3590,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3284\/revisions\/3590"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3284"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3284"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}