{"id":3312,"date":"2022-12-15T10:34:01","date_gmt":"2022-12-15T09:34:01","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/"},"modified":"2025-07-07T16:02:21","modified_gmt":"2025-07-07T14:02:21","slug":"le-retrofit-voiture-electrique-une-pratique-encore-meconnue","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/","title":{"rendered":"Le r\u00e9trofit voiture \u00e9lectrique : une pratique encore m\u00e9connue"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Qu\u2019est-ce que le r\u00e9trofit de la voiture \u00e9lectrique ? Comment convertir sa voiture thermique ? Quel est le prix ? Quelles sont les aides subventionn\u00e9es par l&rsquo;\u00e9tat et comment peut-on en b\u00e9n\u00e9ficier ? Comment les assureurs peuvent aider \u00e0 l\u2019adoption du v\u00e9hicule \u00e9lectrique (prime, franchise, etc) ? On r\u00e9pondra \u00e0 toutes vos questions dans cet article.<\/p>\n<p>Si vous pr\u00e9f\u00e9rez passer \u00e0 l&rsquo;\u00e9lectrique sans renoncer \u00e0 votre moteur thermique, c&rsquo;est possible gr\u00e2ce au r\u00e9trofit r\u00e9git par l&rsquo;arr\u00eat\u00e9 du 13 mars 2020. Le concept est simple\u00a0: vous pouvez transformer votre ancien v\u00e9hicule thermique en v\u00e9hicule \u00e9lectrique. Il faut simplement remplacer le moteur avec un autre \u00e0 batterie.\u00a0Avant la France, 25 autres pays l&rsquo;avaient d\u00e9j\u00e0 l\u00e9galis\u00e9e. Nous allons vous l&rsquo;expliquer.<\/p>\n<h2>R\u00e9trofit \u00e9lectrique : c&rsquo;est quoi ?<\/h2>\n<h3>Le r\u00e9trofit pour transformer votre voiture en v\u00e9hicule \u00e9lectrique<\/h3>\n<p>\u00ab R\u00e9nover \u00bb ou \u00ab r\u00e9trofiter \u00bb est un terme qui vient directement de l&rsquo;anglais et qu\u2019on traduit souvent en fran\u00e7ais par \u00ab r\u00e9nover \u00bb, r\u00e9am\u00e9nagement \u00bb ou \u00ab conversion \u00bb. Selon l&rsquo;Ademe (Agence publique de la transition \u00e9cologique), le r\u00e9trofit \u00e9lectrique est une op\u00e9ration permettant d&rsquo;ajouter, de modifier ou de restaurer des syst\u00e8mes vieillissants tout en conservant leur usage d&rsquo;origine. En d&rsquo;autres termes, c&rsquo;est le remplacement d&rsquo;un moteur \u00e0 combustion interne classique (moteurs thermiques) par un moteur \u00e9lectrique aliment\u00e9 soit par des batteries, soit par des piles \u00e0 hydrog\u00e8ne. Cela implique la modification de la puissance du v\u00e9hicule ou de son autonomie et donc la r\u00e9duction de son temps de recharge par exemple.<\/p>\n<p>Finalement, le r\u00e9trofit est une transformation, ou op\u00e9ration, \u00e0 plusieurs volets. Il permet de conserver sa voiture peu importe la marque (Renault, Nissan\u2026), m\u00eame de collection, et de lui donner un coup de jeune. Il permet aussi de la mettre sur la voie de la transition \u00e9nerg\u00e9tique.<\/p>\n<h3>La r\u00e9novation \u00e9lectrique comporte ses propres d\u00e9fis<\/h3>\n<p>Le r\u00e9trofit s\u2019impose comme une initiative de promotion de la mobilit\u00e9 \u00e9lectrique (gr\u00e2ce \u00e0 une batterie) et de transition \u00e9nerg\u00e9tique. Et ce, sur la base d&rsquo;un certain mod\u00e8le \u00e9conomique. Il n&rsquo;est pas destin\u00e9 \u00e0 durer \u00e9ternellement. C&rsquo;est une \u00e9conomie \u00e9ph\u00e9m\u00e8re qui coexiste avec la fabrication et l&rsquo;acquisition traditionnelles d&rsquo;automobiles neuves d\u00e9j\u00e0 \u00e9lectriques notamment.<\/p>\n<p>D&rsquo;ici 2040, il semble que le r\u00e9trofit \u00e9lectrique pourrait \u00eatre une option viable et pertinente pour les particuliers, professionnels, les entreprises et les collectivit\u00e9s. Pour inciter tout fabricant d\u2019automobiles \u00e0 concevoir des voitures \u00e9lectriques et permettre de convertir l&rsquo;ensemble des flottes thermiques (moteurs \u00e0 essence et diesel).<\/p>\n<p>Une \u00e9tude de l&rsquo;Ademe interroge ainsi ce mod\u00e8le \u00e9conomique.<\/p>\n<p>D&rsquo;un point de vue financier, le r\u00e9trofit est plus avantageux pour les automobiles dont le poids est important. Comme les bus ou les poids lourds de 16 et 19 tonnes.<\/p>\n<p>L&rsquo;achat de camions neufs co\u00fbterait 50 % de plus que l&rsquo;achat de vieux camions fonctionnant sur batteries. D&rsquo;un autre c\u00f4t\u00e9, le r\u00e9trofit voiture \u00e9lectrique pour citadine reviendrait presque aussi cher en co\u00fbt complet au kilom\u00e8tre, que l&rsquo;achat d&rsquo;une \u00e9lectrique et \u00e9cologique toute neuve.<\/p>\n<p>Cependant, l&rsquo;\u00e9tude souligne tout de m\u00eame les points positifs du r\u00e9trofit \u00e9lectrique dont pourraient b\u00e9neficier les utilitaires sur le plan environnemental et professionnel.<\/p>\n<h2>Les avantages de faire un r\u00e9trofit \u00e9lectrique sur sa voiture<\/h2>\n<h3>Les apports \u00e9cologiques du r\u00e9trofit \u00e9lectrique<\/h3>\n<p>Tout d&rsquo;abord, la solution r\u00e9trofit se vante de ses bienfaits environnementaux.<\/p>\n<p>La neutralit\u00e9 carbone d&rsquo;ici 2050 est un objectif important pour tous ceux qui s&rsquo;int\u00e9ressent \u00e0 l&rsquo;att\u00e9nuation du changement climatique.<\/p>\n<p>Le d\u00e9veloppement rapide des zones \u00e0 faibles \u00e9missions mobilit\u00e9s (ZFE-m) a limit\u00e9 la circulation des engins les plus polluants. C\u2019est-\u00e0-dire des automobiles dont l\u2019immatriculation date d\u2019avant 1997. Et ceux dont les certificats sont Crit&rsquo;Air 4 et 5. Les Crit&rsquo;Air 3 les ont rejoints en juillet 2022. Si vous transformez votre voiture thermique d\u2019origine en \u00e9lectrique, alors vous pourrez passer d&rsquo;un Crit&rsquo;Air \u00e9lev\u00e9 \u00e0 un Crit&rsquo;Air 0.<\/p>\n<p>L&rsquo;\u00e9tude de l&rsquo;Ademe examine le r\u00e9trofit voiture \u00e9lectrique sous l&rsquo;angle de la m\u00e9thode ACV (analyse du cycle de vie). Elle prend en compte le dioxyde de carbone \u00e9mis lors de la fabrication d&rsquo;une voiture \u00e9lectrique neuve.<\/p>\n<p>La cible principale du r\u00e9troft \u00e9lectrique \u00e9tant les citadines et les v\u00e9hicules particuliers. C&rsquo;est un \u00e9l\u00e9ment important d&rsquo;une approche d\u2019\u00e9conomie et une marche circulaire de l&rsquo;industrie automobile.<\/p>\n<p>Cette solution vertueuse donne donc une seconde vie \u00e0 ces v\u00e9hicules qui polluent en l\u2019\u00e9tat.<\/p>\n<h3>Le r\u00e9trofit voiture \u00e9lectrique sur le plan \u00e9conomique<\/h3>\n<p>La r\u00e9trofit offre \u00e9galement des avantages \u00e9conomiques importants. L\u2019Association de l\u2019Industrie du R\u00e9trofit \u00e9lectrique (AIRe) qui \u0153uvre pour le d\u00e9veloppement de la fili\u00e8re les approuve.\u00a0Il cr\u00e9e de nouvelles fili\u00e8res et de nouveaux emplois : fabricants de kits de r\u00e9trofit et installateurs.<\/p>\n<p>C&rsquo;est une opportunit\u00e9 importante de cr\u00e9ation d\u2019emplois pour chaque fabricant. Et c&rsquo;est aussi un moyen de doter les garages existants d&rsquo;une activit\u00e9 compl\u00e9mentaire. L&rsquo;entretien des voitures \u00e9lectriques \u00e9tant minime par rapport \u00e0 celui des automobiles gazole ou essence classiques ou de collection.<\/p>\n<p>Cette reconversion rendue possible par le r\u00e9trofit \u00e9lectrique a \u00e9galement permis de lib\u00e9rer les professionnels de tout handicap dans l&rsquo;exercice de leurs m\u00e9tiers. Et notamment les commer\u00e7ants et artisans. Selon une \u00e9tude men\u00e9e par la MAPA (Mutuelle d&rsquo;Assurance Professionnelle) en France, cela repr\u00e9sente la moiti\u00e9 des v\u00e9hicules utilitaires actuellement en circulation. Ce qui \u00e9quivaut \u00e0 plus de 18 000 moteurs autoris\u00e9s au r\u00e9trofit voiture \u00e9lectrique.<\/p>\n<h2>Cadre r\u00e9glementaire du r\u00e9trofit en France<\/h2>\n<p>Le d\u00e9cret du 13 mars 2020 encadre la conversion d&rsquo;une voiture thermique en \u00e9lectrique en France. Ce d\u00e9cret pr\u00e9voit un processus administratif simple et rapide. Il offre des garanties tant pour le fournisseur que pour l&rsquo;utilisateur final.<\/p>\n<p>Le processus de transformation est environ au prix de 8 000 euros pour une voiture \u00e0 gaz. Et de 22 000 euros pour une voiture diesel ou essence. Il ne n\u00e9cessite pas de modification du certificat de contr\u00f4le technique de l&rsquo;engin et n&rsquo;est donc pas soumis \u00e0 l&rsquo;obligation de d\u00e9clarer la modification \u00e0 la pr\u00e9fecture. Et c&rsquo;est l&rsquo;entreprise ayant effectu\u00e9e le r\u00e9trofit de l&rsquo;engin qui se charge de son homologation.<\/p>\n<p>Il vous faut aussi actualiser votre carte grise. En effet, la puissance et la motorisation figurent dessus. Vous disposez d\u2019un d\u00e9lai d\u2019un mois pour actualiser votre carte grise autrement vous vous exposez \u00e0 une demande forfaitaire.<\/p>\n<p>Votre r\u00e9trofit voiture \u00e9lectrique n\u00e9cessite de souscrire une nouvelle assurance. Effectivement, avec son moteur tout neuf, il faut d\u00e9clarer ce nouveau v\u00e9hicule \u00e0 votre assurance auto. Sachez que le prix sera sans doute moindre. La raison est qu\u2019en raison de leur faible autonomie et de la recharge fr\u00e9quente, les v\u00e9hicules \u00e9lectriques parcourent moins de kilom\u00e8tres. Ils s\u2019exposent \u00e0 moins de risques d\u2019accidents.<\/p>\n<h2><strong>Est-ce que ma voiture est-t-elle r\u00e9trofitable ?<\/strong><\/h2>\n<p>La premi\u00e8re \u00e9tape dans le processus de transformation consiste \u00e0 d\u00e9terminer si votre voiture peut en b\u00e9n\u00e9ficier ou non. Malheureusement, toutes les voitures ne sont pas \u00e9ligibles au r\u00e9trofit voiture \u00e9lectrique.<\/p>\n<p>Voici les questions qui se posent\u00a0:<\/p>\n<h3>Mon v\u00e9hicule est-il \u00e9ligible au r\u00e9trofit selon la r\u00e9glementation en vigueur ?<\/h3>\n<p>Seules les voitures appartenant aux cat\u00e9gories L, M, N peuvent faire l&rsquo;objet d&rsquo;un r\u00e9trofit \u00e9lectrique.<\/p>\n<p>Voici le d\u00e9tail de ces types de cat\u00e9gories\u00a0:<\/p>\n<ul>\n<li>La cat\u00e9gorie L comprend les motocyclettes, les cyclomoteurs et les v\u00e9hicules tout-terrain (VTT). Ainsi que les petites automobiles \u00e0 trois ou quatre roues.<\/li>\n<li>Les autos de la cat\u00e9gorie N comprennent les camions ou camionnettes destin\u00e9s au transport de marchandises.<\/li>\n<li>Les v\u00e9hicules de la cat\u00e9gorie M sont des v\u00e9hicules con\u00e7us pour le transport de personnes et correspondant au moins quatre roues.<\/li>\n<\/ul>\n<p>Par cons\u00e9quent, les cat\u00e9gories de autos qui sont exclues sont celles comprenant les voitures anciennes (cat\u00e9gorie Z) et les machines agricoles.<\/p>\n<p>Il existe de nombreux engins que vous pouvez transformer en moyen de transport \u00e9lectrique. Et de nombreux kits de conversion sont disponibles. Transition One est une r\u00e9d\u00e9rence en mati\u00e8re de retrofit. En proposant une technologie adapt\u00e9e et qui r\u00e9pond \u00e0 l\u2019homologation obligatoire.<\/p>\n<p>Parmi les mod\u00e8les d\u2019autos les plus int\u00e9ressants \u00e0 modifier, on retrouve la Citro\u00ebn C4 Cactus. Ce mod\u00e8le est \u00e9galement un kit de conversion. Cette voiture a \u00e9t\u00e9 lanc\u00e9e en 2014 et est tr\u00e8s populaire. \u00a0La Peugeot 408 est un engin pour lequel vous trouverez de nombreux kits de conversion.<\/p>\n<p>Le kit peut se monter sur le moteur. Ce r\u00e9trofit peut se r\u00e9aliser par une entreprise qui en produit (comme Transition One). Un m\u00e9canicien peut \u00e9galement le faire.<\/p>\n<h3>L&rsquo;immatriculation de mon v\u00e9hicule a \u00e9t\u00e9 faite en France et quand ?<\/h3>\n<p>La proc\u00e9dure de r\u00e9trofit est strictement encadr\u00e9e, la voiture doit \u00eatre immatricul\u00e9e en France. Vous devez avoir fait l\u2019inscription il y a au moins cinq ans.<\/p>\n<p>On fait une exception pour les autos de cat\u00e9gorie L ayant trois ans d&rsquo;anciennet\u00e9 si le constructeur s&rsquo;engage \u00e0 raccourcir la p\u00e9riode de garantie.<\/p>\n<h2>Assurance auto pour v\u00e9hicule r\u00e9trofit\u00e9<\/h2>\n<p>Le r\u00e9trofit est une modification de votre moyen de transport : il s&rsquo;agit donc d&rsquo;un \u00e9v\u00e9nement assur\u00e9. Il impacte votre contrat d&rsquo;assurance auto, m\u00eame s&rsquo;il s&rsquo;agit d&rsquo;un contrat tous risques. Vous pourrez toujours b\u00e9nificier d&rsquo;une garantie.<\/p>\n<p>Mais si suite au r\u00e9trofit votre v\u00e9hicule r\u00e9pond aux crit\u00e8res d&rsquo;un engin autonome, alors votre v\u00e9hicule est un v\u00e9hicule autonome.<\/p>\n<p>Les contrats d\u2019assurance auto ne couvrent pas les v\u00e9hicules autonomes. M\u00eame en formule tous risques. Vous devrez donc compl\u00e9ter votre contrat par une assurance auto sp\u00e9cifique aux autos autonomes.<\/p>\n<h2>Quelles sont les primes d&rsquo;assurance pour une voiture modernis\u00e9e ?<\/h2>\n<p>Une prime d&rsquo;assurance est sp\u00e9cifique \u00e0 chaque automobile et varie en fonction de chaque compagnie et de chaque r\u00e9gion. Toutes les compagnies acceptent les r\u00e9trofits. En effet, le r\u00e9trofit n\u2019augmente pas pas le risque.<\/p>\n<p>Le r\u00e9trofit est une transformation en v\u00e9hicule \u00e9lectrique. Il peut m\u00eame abaisser le risque du fait que le v\u00e9hicule parcourt moins de kilom\u00e8tres d\u2019un coup.<\/p>\n<p>Si vous voulez vendre votre voiture, il est pr\u00e9f\u00e9rable de le faire avant de la r\u00e9am\u00e9nager. Car il est possible que moins d&rsquo;acheteurs s\u2019int\u00e9ressent \u00e0 votre bien. Et le retrofit peut r\u00e9duire le prix de vente de votre bien. La transformation ne peut augmenter sa valeur que si elle est rare.<\/p>\n<h2>Quelles sont les aides propos\u00e9es pour le r\u00e9trofit ?<\/h2>\n<p>Le gouvernement accorde une subvention d&rsquo;un montant 10 000 euros pour aider \u00e0 compenser le prix du r\u00e9trofit. Le r\u00e9trofit fonctionne mieux avec le leasing, d&rsquo;autant plus que le processus de r\u00e9trofit n&rsquo;est pas exempt de d\u00e9fauts.<\/p>\n<p>Mais il pr\u00e9sente de nombreux points positifs. Si le co\u00fbt initial peut sembler prohibitif, \u00e0 long terme, vous pourriez r\u00e9aliser des \u00e9conomies. Si vous choisissez cette voie, attention \u00e0 trouver le kit correspondant \u00e0 la marque de votre auto (Renault, Citroen, Peugeot, etc).[\/vc_column_text]<\/p>\n<p><strong>A lire aussi:<\/strong><\/p>\n<ul>\n<li>La voiture \u00e9lectrique : un march\u00e9 grandissant<\/li>\n<li>Quels sont les diff\u00e9rents types de carburant ?<\/li>\n<li>Changement de voiture : que faire de son assurance ?<\/li>\n<li>Contr\u00f4le technique en France : r\u00e9glementation, v\u00e9hicules et prix<\/li>\n<\/ul>\n<p>[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Qu\u2019est-ce que le r\u00e9trofit de la voiture \u00e9lectrique ? Comment convertir sa voiture thermique ? Quel est le prix ? Quelles sont les aides subventionn\u00e9es par l&rsquo;\u00e9tat et comment peut-on en b\u00e9n\u00e9ficier ? Comment les assureurs peuvent aider \u00e0 l\u2019adoption du v\u00e9hicule \u00e9lectrique (prime, franchise, etc) ? On r\u00e9pondra \u00e0 toutes vos questions dans cet [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le r\u00e9trofit voiture \u00e9lectrique : une pratique encore m\u00e9connue - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Qu\u2019est-ce que le r\u00e9trofit de la voiture \u00e9lectrique ? Quel est le prix ? Les aides ? Comment les assureurs r\u00e9agissent ? On vous dit tout !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00e9trofit voiture \u00e9lectrique : une pratique encore m\u00e9connue - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Qu\u2019est-ce que le r\u00e9trofit de la voiture \u00e9lectrique ? Quel est le prix ? Les aides ? Comment les assureurs r\u00e9agissent ? On vous dit tout !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-15T09:34:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"9 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/\",\"name\":\"Le r\\u00e9trofit voiture \\u00e9lectrique : une pratique encore m\\u00e9connue - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2022-12-15T09:34:01+00:00\",\"dateModified\":\"2025-07-07T14:02:21+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Qu\\u2019est-ce que le r\\u00e9trofit de la voiture \\u00e9lectrique ? Quel est le prix ? Les aides ? Comment les assureurs r\\u00e9agissent ? On vous dit tout !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/le-retrofit-voiture-electrique-une-pratique-encore-meconnue\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3312"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3312"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3312\/revisions"}],"predecessor-version":[{"id":3604,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3312\/revisions\/3604"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3312"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}