{"id":3628,"date":"2023-06-06T03:28:38","date_gmt":"2023-06-06T01:28:38","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-et-relogement-apres-sinistre\/"},"modified":"2025-07-07T16:02:23","modified_gmt":"2025-07-07T14:02:23","slug":"assurance-et-relogement-apres-sinistre","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/assurance-et-relogement-apres-sinistre\/","title":{"rendered":"Assurance et relogement apr\u00e8s sinistre"},"content":{"rendered":"<p>[vc_row][vc_column][vc_column_text]<\/p>\n<h2>Relogement apr\u00e8s sinistre : Que dit l&rsquo;assurance ?<\/h2>\n<p>De nombreuses assurances multirisques habitation prennent en charge les frais de d\u00e9m\u00e9nagement et de relogement si le bien devient inhabitable du fait d&rsquo;un risque assur\u00e9. Cela permet aux sinistr\u00e9s de se reloger temporairement en attendant la fin de l&rsquo;\u00e9valuation des d\u00e9g\u00e2ts et les travaux de r\u00e9novation du ou des logements.<\/p>\n<p>Des questions se posent sur le relogement apr\u00e8s un d\u00e9g\u00e2t dans un logement : A qui demander un relogement ? Comment se passe un relogement suite \u00e0 des d\u00e9g\u00e2ts des eaux ou \u00e0 un sinistre important ? Comment faire quand les d\u00e9g\u00e2ts touchent aussi les logements des voisins ? Qui paye le loyer d&rsquo;un locataire en cas de relogement en zone urbaine et que devient le bail de location ? Quels sont les cas o\u00f9 le relogement est obligatoire pour un locataire ou un propri\u00e9taire ?<\/p>\n<h2>Le relogement par la compagnie assurance est-il syst\u00e9matique ?<\/h2>\n<p>Le relogement est une offre facultative ! L&rsquo;assureur n&rsquo;a donc aucune obligation d&rsquo;indiquer cette clause. C&rsquo;est donc au locataire ou au propri\u00e9taire de v\u00e9rifier si la police d&rsquo;assurance actuelle couvre ce risque avec une clause relogement en zone urbaine ou proche de votre quartier.<\/p>\n<p>Demandez directement \u00e0 votre assureur si vous pouvez b\u00e9n\u00e9ficier de l\u2019assistance relogement si jamais vous avez un doute. Vous pouvez faire \u00e9galement une simulation en ligne tr\u00e8s rapide aupr\u00e8s d&rsquo;un assureur qui vous proposera un tarif pour un contrat multirisque habitation. D&rsquo;ailleurs, il est important de pr\u00e9ciser que la t\u00e2che se complexifie pour trouver des logements en ville, proches de Paris, ou en milieu urbain. En effet, il est plus simple de trouver des appartements en milieu rural ou des appartements en province.<\/p>\n<p>Que vous soyez locataire ou propri\u00e9taire, vous pouvez \u00e9galement changer d&rsquo;assurance habitation si votre assureur actuel ne propose pas l&rsquo;option relogement. C&rsquo;est simple, il suffit de remplir un formulaire en ligne en renseignant quelques informations et un courtier de votre r\u00e9gion vous contactera pour prendre rendez-vous et vous proposer les meilleures garanties de logements, que vous soyez locataire ou propri\u00e9taire.<\/p>\n<h2>Que couvre l\u2019assistance relogement de votre assurance habitation ?<\/h2>\n<p>On distingue 2 types de prise en charge dans le cadre d&rsquo;une garantie Multirisque Habitation ou MRH pour les m\u00e9nages :<\/p>\n<ul>\n<li>L&rsquo;assistance relogement d&rsquo;urgence<\/li>\n<\/ul>\n<p>En cas d\u2019impossibilit\u00e9 de mise en s\u00e9curit\u00e9 des logements ou de r\u00e9paration provisoire des d\u00e9g\u00e2ts dans votre logement, pas de panique ! L&rsquo;assureur organise et prend en charge le relogement en proposant la r\u00e9servation d\u2019un h\u00f4tel situ\u00e9 \u00e0 proximit\u00e9 de votre logement, dans la limite du plafond pr\u00e9vu. L&rsquo;assureur tente de trouver un logement dans le m\u00eame quartier de la ville, commune ou milieu urbain que vous habitez pour faciliter vos d\u00e9placements et votre vie au quotidien. Votre niveau de ressources et vie de famille sont \u00e9galement pris en compte pour choisir des logements qui conviennent, notamment si le relogement est de longue dur\u00e9e.<\/p>\n<p>Certaines compagnies proposent des services de relogement d&rsquo;urgence 24h\/24 et 7j\/7. Il vous suffit de les appeler pour r\u00e9server un relogement d&rsquo;urgence : dans un h\u00f4tel dans le m\u00eame quartier, dans des logements vacants ou dans des logements sociaux hlm dans la m\u00eame ville que votre logement endommag\u00e9.<\/p>\n<ul>\n<li>Les frais de relogement longue dur\u00e9e<\/li>\n<\/ul>\n<p>Si vous ne pouvez pas vivre dans votre logement actuel pendant une p\u00e9riode prolong\u00e9e, votre assureur peut vous proposer une alternative plus permanente qu&rsquo;un relogement d&rsquo;urgence. Si l&rsquo;assur\u00e9 prend en charge les frais de d\u00e9m\u00e9nagement temporaire, l&rsquo;assureur doit les couvrir dans des conditions identiques.<\/p>\n<p>Selon la situation des m\u00e9nages &#8211; locataire ou propri\u00e9taire &#8211; les frais de relogement peuvent \u00eatre d\u00e9ductibles ou non :<\/p>\n<ul>\n<li>Le montant du loyer que vous auriez d\u00fb payer s&rsquo;il n&rsquo;y avait pas eu de d\u00e9g\u00e2t, si vous \u00e9tiez locataire du logement.<\/li>\n<li>La valeur locative des biens endommag\u00e9s si vous en \u00eates propri\u00e9taire.<\/li>\n<\/ul>\n<h2>L\u2019assistance relogement : bien v\u00e9rifier les conditions<\/h2>\n<p>Cependant, ces d\u00e9penses de d\u00e9m\u00e9nagement et du projet de relogement ne sont pas toujours clairement d\u00e9finies dans les assurances. Les conditions sont vagues. Il faut alors que les doutes profitent \u00e0 l&rsquo;assur\u00e9. Pour rappel de la loi, l\u2019Article L211-1 du Code de la Consommation dispose que \u201cLes clauses des contrats propos\u00e9s par les professionnels aux consommateurs doivent \u00eatre pr\u00e9sent\u00e9es et r\u00e9dig\u00e9es de fa\u00e7on claire et compr\u00e9hensible. Elles s\u2019interpr\u00e8tent en cas de doute dans le sens le plus favorable au consommateur\u201d.<\/p>\n<h3>A titre d&rsquo;exemple<\/h3>\n<p>Un dossier r\u00e9cent a \u00e9t\u00e9 trait\u00e9 par le m\u00e9diateur des assurances o\u00f9 un incendie s&rsquo;est d\u00e9clar\u00e9 dans la r\u00e9sidence principale (le bien assur\u00e9) du locataire. Il vivait depuis plusieurs mois dans un appartement inhabitable. Son bailleur social lui a trouv\u00e9 en urgence un autre appartement, mais \u00e0 un co\u00fbt plus \u00e9lev\u00e9.<\/p>\n<p>Cependant, ce dernier a sign\u00e9 une assurance garantissant des frais suppl\u00e9mentaires tels que des frais de d\u00e9m\u00e9nagement. Il a donc demand\u00e9 le remboursement de ces frais de relogement. La compagnie d&rsquo;assurance a refus\u00e9 cette demande, arguant que \u00ab votre contrat garantit des frais suppl\u00e9mentaires tels des frais de d\u00e9m\u00e9nagement, c&rsquo;est-\u00e0-dire le montant du loyer que vous avez engag\u00e9 pour vous installer dans des conditions identiques \u00bb.<\/p>\n<p>Au jour de votre incident, vous habitiez un appartement compos\u00e9 de quatre pi\u00e8ces principales. On vous propose un nouvel appartement compos\u00e9 de cinq pi\u00e8ces. Il en r\u00e9sulte des diff\u00e9rences dans les conditions de relogement.<\/p>\n<p>En ne d\u00e9finissant pas clairement la notion de \u201cconditions identiques\u201d de logements comme condition de garantie, le m\u00e9diateur a estim\u00e9 que celle-ci doit \u00eatre consid\u00e9r\u00e9e comme \u00e9tant remplie, d\u00e8s lors que la possibilit\u00e9 de trouver des logements dans le m\u00eame quartier, zone urbaine, ville ou commune, de m\u00eame superficie, avec le m\u00eame agencement, pour un loyer similaire dans ce type de situation d\u2019urgence apr\u00e8s le d\u00e9g\u00e2t rel\u00e8ve de l\u2019impossible ! En effet, apr\u00e8s l&rsquo;incendie survenu dans le logement de ses locataires, le bailleur a trouv\u00e9 une solution d&rsquo;urgence en attribuant au locataire un logement similaire \u00e0 celui qu&rsquo;il occupait auparavant.<\/p>\n<p>Compte tenu du contexte du sinistre et de la situation v\u00e9cue par les deux parties, et dans un souci d&rsquo;apaisement, le m\u00e9diateur a invit\u00e9 l&rsquo;assureur, pendant la dur\u00e9e des travaux, et dans les limites fix\u00e9es par le contrat, \u00e0 prendre en charge les frais de relogement de l&rsquo;assur\u00e9 et de sa famille.<\/p>\n<p>Les assurances ne sont pas toujours parfaitement r\u00e9dig\u00e9es clairement concernant les logements. C&rsquo;est pourquoi il est souvent conseill\u00e9 de se faire accompagner par un expert. Ainsi, le doute de l\u2019assistance logement profite \u00e0 la victime.<\/p>\n<h2>Que faire si l&rsquo;assureur ne couvre pas le relogement d&rsquo;urgence ?<\/h2>\n<p>Si l&rsquo;assureur ne couvre pas les frais de relogement c&rsquo;est que l&rsquo;assur\u00e9 est couvert \u00e0 minima par l&rsquo;assurance. Il n&rsquo;a donc aucune garantie de pouvoir \u00eatre relog\u00e9. N&rsquo;ayant pas l\u2019assistance relogement, il ne peut donc pas avoir droit au remboursement des frais de d\u00e9m\u00e9nagement et de recherche d&rsquo;un autre appartement pour se loger apr\u00e8s un sinistre.<\/p>\n<p>Il est donc conseill\u00e9 de se renseigner concernant l\u2019assistance relogement, m\u00eame si la prime d&rsquo;assurance de la cotisation est un peu plus \u00e9lev\u00e9e \u00e0 payer. C&rsquo;est une s\u00e9curit\u00e9 surtout si vous vivez dans un appartement qui n&rsquo;est pas en tr\u00e8s bon \u00e9tat.<\/p>\n<p>Si vous \u00eates locataire, vous pouvez \u00e9galement contacter une association de consommateurs. Cela vous permet de d\u00e9fendre vos droits en cas de sinistre important si vous constatez des d\u00e9faillances au niveau du fonctionnement au niveau de l&rsquo;\u00e9lectricit\u00e9 (incendie) ou de la toiture (d\u00e9g\u00e2t des eaux). Ces r\u00e9parations incombent au propri\u00e9taire bailleur. En effet, ce dernier doit louer un bien en bon \u00e9tat d&rsquo;usage, sans mettre la s\u00e9curit\u00e9 des locataires en danger.<\/p>\n<h2><strong>Expertise des d\u00e9g\u00e2ts avant le relogement<\/strong><\/h2>\n<p>Avant toute indemnisation, l&rsquo;assur\u00e9 &#8211; les m\u00e9nages locataires ou propri\u00e9taires &#8211; doit effectuer une d\u00e9claration aupr\u00e8s de sa compagnie d&rsquo;assurances. D\u00e8s r\u00e9ception de la d\u00e9claration de sinistre, l&rsquo;assureur fera intervenir un expert pour constater les d\u00e9g\u00e2ts dans le logement. Il intervient sur les murs, sur vos affaires personnelles et les dommages \u00e9ventuels occasionn\u00e9s sur les logements des voisins. En effet, certains d\u00e9g\u00e2ts peuvent \u00eatre tr\u00e8s importants entrainant une r\u00e9novation totale du logement, voire une destruction du logement dans certains cas.<\/p>\n<p>L&rsquo;expert va \u00e9valuer les cons\u00e9quences des d\u00e9g\u00e2ts suivant le contrat d&rsquo;assurance habitation sign\u00e9 avec le locataire ou le propri\u00e9taire. Dans le cadre de dommages importants sur l\u2019habitat et \u00e0 la suite du constat, l&rsquo;assureur prendra la d\u00e9cision du relogement dans les conditions qu&rsquo;il choisira.<\/p>\n<p>Le r\u00f4le de l\u2019expert, comme lors d&rsquo;un sinistre auto est de :<\/p>\n<ul>\n<li>D\u00e9terminer les causes et l&rsquo;origine des dommages dans le logement des m\u00e9nages et\/ou logements voisins ;<\/li>\n<li>Evaluer les biens endommag\u00e9s dans le logement et\/ou logements voisins ;<\/li>\n<li>Informer les locataires ou propri\u00e9taires de leurs droits conform\u00e9ment \u00e0 la loi<\/li>\n<li>Pr\u00e9coniser des mesures conservatoires<\/li>\n<\/ul>\n<p>Les m\u00e9nages, que ce soit un locataire ou un propri\u00e9taire sinistr\u00e9, doivent dans la mesure du possible r\u00e9cup\u00e9rer les documents et papiers justificatifs. Notre conseil : Prendre des photos les d\u00e9g\u00e2ts du logement ou des logements.<\/p>\n<h2><strong>Les bons r\u00e9flexes \u00e0 avoir suite \u00e0 des d\u00e9g\u00e2ts logements<\/strong><\/h2>\n<p>Votre logement a subi un d\u00e9g\u00e2t des eaux? Un incendie? Une explosion avec bris de glace ? Ou un autre sinistre important qui touche les autres logements et l&rsquo;immeuble ? Le premier r\u00e9flexe est de contacter votre assureur pour faire une d\u00e9claration. Vous \u00eates locataires? Contactez le propri\u00e9taire bailleur, l&rsquo;agence immobili\u00e8re qui a fait le bail ou le syndic de copropri\u00e9t\u00e9.<\/p>\n<p>Les premiers gestes \u00e0 faire apr\u00e8s un sinistre dans un logement sont de :<\/p>\n<ul>\n<li>s\u00e9curiser le logement : coupez l&rsquo;eau, le tableau \u00e9lectrique&#8230;<\/li>\n<li>informer rapidement vos voisins<\/li>\n<li>\u00e9tablir un constat amiable m\u00eame si vous n&rsquo;\u00eates pas responsable des dommages<\/li>\n<li>prendre des photos pour faire un inventaire des dommages subis<\/li>\n<li>regrouper vos documents et justificatifs (factures, photos de vos meubles et objets de valeur, bail de location&#8230;)<\/li>\n<\/ul>\n<p>Une fois votre assureur inform\u00e9, l&rsquo;expert sera mandat\u00e9 pour constater les d\u00e9g\u00e2ts.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<p><em><strong>A lire aussi :<\/strong><\/em><\/p>\n<ul>\n<li>Souscrire une assurance habitation pour inondation de cave<\/li>\n<li>Catastrophe naturelle en assurance habitation : la franchise s&rsquo;applique-t-elle ?<\/li>\n<li>Assurance habitation : Objets de valeur<\/li>\n<li>Comment d\u00e9clarer \u00e0 son assurance habitation des d\u00e9g\u00e2ts caus\u00e9s par son chien ?<\/li>\n<li>Quelle assurance multirisque habitation choisir pour un \u00e9tudiant ?<\/li>\n<li>Assurance multirisque habitation : tout ce qu\u2019il faut savoir<\/li>\n<li>Tout savoir sur le bris de glace en assurance habitation et ses modalit\u00e9s<\/li>\n<li>Assurance habitation et remboursement \u00e9lectrom\u00e9nager : tout savoir<\/li>\n<li>Assurance habitation : diff\u00e9rences entre r\u00e9sidence secondaire et principale<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text] Relogement apr\u00e8s sinistre : Que dit l&rsquo;assurance ? De nombreuses assurances multirisques habitation prennent en charge les frais de d\u00e9m\u00e9nagement et de relogement si le bien devient inhabitable du fait d&rsquo;un risque assur\u00e9. Cela permet aux sinistr\u00e9s de se reloger temporairement en attendant la fin de l&rsquo;\u00e9valuation des d\u00e9g\u00e2ts et les travaux de r\u00e9novation [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[13],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Assurance et relogement apr\u00e8s sinistre - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Le relogement apr\u00e8s un sinistre n&#039;est pas syst\u00e9matique par l&#039;assurance habitation. Voici les conseils d&#039;un assureur exp\u00e9riment\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Assurance et relogement apr\u00e8s sinistre - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Le relogement apr\u00e8s un sinistre n&#039;est pas syst\u00e9matique par l&#039;assurance habitation. Voici les conseils d&#039;un assureur exp\u00e9riment\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-06T01:28:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:23+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"9 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/\",\"name\":\"Assurance et relogement apr\\u00e8s sinistre - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2023-06-06T01:28:38+00:00\",\"dateModified\":\"2025-07-07T14:02:23+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Le relogement apr\\u00e8s un sinistre n'est pas syst\\u00e9matique par l'assurance habitation. Voici les conseils d'un assureur exp\\u00e9riment\\u00e9\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/assurance-et-relogement-apres-sinistre\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3628"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3628"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3628\/revisions"}],"predecessor-version":[{"id":3680,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3628\/revisions\/3680"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3628"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}