{"id":3678,"date":"2024-03-05T05:49:07","date_gmt":"2024-03-05T04:49:07","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/accident-avec-un-chien-qui-est-responsable\/"},"modified":"2025-07-07T16:02:28","modified_gmt":"2025-07-07T14:02:28","slug":"accident-avec-un-chien-qui-est-responsable","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/accident-avec-un-chien-qui-est-responsable\/","title":{"rendered":"Qui est responsable lors d\u2019un accident avec un chien\u00a0?"},"content":{"rendered":"<h2>Accident avec un chien : Qui est responsable ?<\/h2>\n<p>Le propri\u00e9taire d\u2019un chien doit toujours conserver le contr\u00f4le de son animal domestique afin d\u2019\u00e9viter tout accident. Toutefois personne n\u2019est \u00e0 l\u2019abri d\u2019un accident ou d\u2019une collision. Mais alors qui est responsable lors d\u2019un accident avec un chien\u00a0? Comment fonctionnent les assurances\u00a0? Quelles sont les d\u00e9marches \u00e0 r\u00e9aliser\u00a0? On fait le point\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<h2>Accident avec un chien sur la voie publique : Quelle responsabilit\u00e9 ?<\/h2>\n<p>Selon <u>l\u2019article 1243 du Code Civil<\/u>, le responsable d\u2019un accident provoqu\u00e9 par un chien est son propri\u00e9taire. N\u00e9anmoins, cela va d\u00e9pendre des circonstances et du lieu de l\u2019accident.<\/p>\n<p>En effet, si vous renversez un chien sur la route c\u2019est-\u00e0-dire sur une voie publique, la responsabilit\u00e9 de l\u2019accident varie selon que l\u2019animal \u00e9tait en laisse ou non :<\/p>\n<ul>\n<li><strong>Accident avec un chien tenu en laisse\u00a0:<\/strong> Dans ce cas, c\u2019est le conducteur qui est responsable de l\u2019accident. Ici, c\u2019est donc la responsabilit\u00e9 civile de son assurance auto qui prendra en charge l\u2019indemnisation du propri\u00e9taire du chien, notamment en ce qui concerne les frais de v\u00e9t\u00e9rinaire.<\/li>\n<li><strong>Accident avec un chien errant <\/strong>: Un animal domestique est consid\u00e9r\u00e9 \u00ab en divagation \u00bb d\u00e8s lors que ce dernier n\u2019est pas tenu en laisse et se situe \u00e0 plus de 100 m\u00e8tres de son ma\u00eetre. Dans ce cas, c\u2019est le propri\u00e9taire du chien qui est tenu responsable de l\u2019accident et des dommages caus\u00e9s lors de la collision. Ici, le conducteur est non responsable. C\u2019est donc la garantie responsabilit\u00e9 civile de son assurance habitation qui entre en jeu. Et cela, qu\u2019il s\u2019agisse de dommages corporels ou mat\u00e9riels. Attention, pour cela, il faut pr\u00e9venir la compagnie d\u2019assurance de l\u2019existence de votre chien et donc avoir souscrit les garanties n\u00e9cessaires.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Accident avec un chien sur une propri\u00e9t\u00e9 priv\u00e9e : Quelle responsabilit\u00e9 ?<\/h2>\n<p>Contrairement \u00e0 la voie publique, un animal domestique peut \u00eatre totalement libre sur un terrain priv\u00e9. Par cons\u00e9quent, en cas d\u2019accident ce sera le conducteur qui sera responsable.<\/p>\n<p>En effet, si un chien est renvers\u00e9 ou \u00e9cras\u00e9 sur un terrain priv\u00e9, la responsabilit\u00e9 civile de la MRH (multirisque habitation) du conducteur prend en charge les frais li\u00e9s \u00e0 la collusion. Par la suite, la MRH se retourne contre l\u2019assurance auto du conducteur pour le remboursement puisqu\u2019elle a eu lieu avec le v\u00e9hicule du conducteur responsable.<\/p>\n<p><em>Bon \u00e0 savoir\u00a0: En fonction des circonstances de l\u2019accident, le propri\u00e9taire du chien peut se retourner contre l\u2019automobiliste et lui r\u00e9clamer des dommages et int\u00e9r\u00eats pour le pr\u00e9judice subi, notamment si le chien est d\u00e9c\u00e9d\u00e9.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Chien \u00e9cras\u00e9 par une voiture : Comment fonctionnent les assurances ?<\/h2>\n<p>Lors d\u2019un accident avec un chien, ce dernier risque malheureusement de subir plus de d\u00e9g\u00e2ts que le v\u00e9hicule lui-m\u00eame. N\u00e9anmoins, que se passe-t-il lors l\u2019auto a \u00e9galement subi des dommages\u00a0? Quelle assurance entre en jeu\u00a0? Et bien cela va d\u00e9pendre si le propri\u00e9taire du chien est connu ou non.<\/p>\n<p>&nbsp;<\/p>\n<h3>L\u2019identit\u00e9 du propri\u00e9taire du chien n\u2019est pas connue<\/h3>\n<p>Dans ce cas, c\u2019est l\u2019assurance auto du conducteur qui prend en charge les dommages selon les garanties souscrites, \u00e0 savoir\u00a0:<\/p>\n<ul>\n<li><strong>Assurance au tiers\u00a0: <\/strong>Le conducteur peut se rapprocher du FGAO (fonds de garantie des assurances obligatoires de dommages) et demander le remboursement des dommages. Une franchise devra \u00eatre r\u00e9gl\u00e9e. Cette garantie intervient uniquement si vous avez subi des dommages corporels ou si le propri\u00e9taire du chien n\u2019a pas d\u00e9clar\u00e9 son animal \u00e0 sa MRH.<\/li>\n<li><strong>Assurance tous risques\u00a0:<\/strong> Un expert est alors mandat\u00e9 par l\u2019assurance afin d\u2019estimer le montant des dommages et par cons\u00e9quent le montant de l\u2019indemnisation. Attention, une franchise peut s&rsquo;appliquer.<\/li>\n<\/ul>\n<p>Pour identifier un propri\u00e9taire de chien, vous pouvez v\u00e9rifier le collier de l\u2019animal qui peut comporter des coordonn\u00e9es. Mais aussi v\u00e9rifier le num\u00e9ro ICAD, il s\u2019agit d\u2019un tatouage \u00e0 l\u2019int\u00e9rieur de l\u2019oreille permettant l\u2019identification du chien. Ensuite, vous d\u00e9clarez l\u2019animal aupr\u00e8s du fichier d\u2019identification ICAD.<\/p>\n<p>&nbsp;<\/p>\n<h3>L\u2019identit\u00e9 du propri\u00e9taire du chien est connue<\/h3>\n<p>Si le propri\u00e9taire est identifi\u00e9, alors c\u2019est la responsabilit\u00e9 civile de son assurance habitation qui va prendre en charge l\u2019indemnisation du conducteur. Cette derni\u00e8re peut \u00e9ventuellement se compl\u00e9ter avec l&rsquo;assurance responsabilit\u00e9 civile du chien.<\/p>\n<p><em>Bon \u00e0 savoir : \u00c9craser un animal domestique n\u2019aura pas d\u2019impact sur votre contrat d\u2019assurance auto si vous n\u2019\u00eates pas responsable de l\u2019accident. En revanche, si vous \u00eates responsable, alors vous \u00e9copez d\u2019un malus \u00e0 hauteur de 25%. Sauf si vous avez un bonus de 0,50 pendant plus de trois ans. <\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Comment d\u00e9clarer un accident impliquant un chien\u2009?<\/h2>\n<p>Comme tout accident, vous devez le d\u00e9clarer \u00e0 votre assurance dans les 5 jours ouvr\u00e9s Pour cela, vous pouvez\u00a0:<\/p>\n<ul>\n<li>D\u00e9clarer le sinistre par t\u00e9l\u00e9phone,<\/li>\n<li>Remplir le constat via un formulaire en ligne,<\/li>\n<li>Envoyer le constat par lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception,<\/li>\n<li>Se rendre directement chez votre assureur<\/li>\n<\/ul>\n<p>Le propri\u00e9taire doit signer le constat amiable.<\/p>\n<p>&nbsp;<\/p>\n<h2>Quelle assurance pour prot\u00e9ger son chien en cas d\u2019accident ?<\/h2>\n<p>Si vous \u00eates propri\u00e9taire d\u2019un animal domestique, vous devez le d\u00e9clarer \u00e0 votre assureur pour \u00e9tendre les garanties de votre assurance habitation. En effet, il permet ainsi la prise en charge des victimes en cas de dommages.<\/p>\n<p>Mais vous pouvez aussi opter pour la garantie responsabilit\u00e9 civile d\u2019un chien. Elle est facultative sauf pour les chiens de cat\u00e9gories 1 et 2 consid\u00e9r\u00e9s comme dangereux<strong>. <\/strong><\/p>\n<p>Pour un chien hors cat\u00e9gorie 1 et 2, une assurance RC est de 3 \u20ac par mois pour une assurance individuelle. Cela peut atteindre 20 \u20ac par mois si vous la couplez \u00e0 une assurance sant\u00e9.<\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 comparer les offres d\u2019assurance pour couvrir vos animaux domestiques gr\u00e2ce \u00e0 notre simulateur\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<p><strong>A lire aussi :<\/strong><\/p>\n<ul>\n<li>Comment assurer son chien ?<\/li>\n<li>Assurance au tiers et accident responsable<\/li>\n<li>1er accident responsable malus : ce qu\u2019il faut conna\u00eetre<\/li>\n<li>Accident responsable : malus auto et cons\u00e9quences sur votre assurance<\/li>\n<li>Tout savoir sur un accident non responsable<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Accident avec un chien : Qui est responsable ? Le propri\u00e9taire d\u2019un chien doit toujours conserver le contr\u00f4le de son animal domestique afin d\u2019\u00e9viter tout accident. Toutefois personne n\u2019est \u00e0 l\u2019abri d\u2019un accident ou d\u2019une collision. Mais alors qui est responsable lors d\u2019un accident avec un chien\u00a0? Comment fonctionnent les assurances\u00a0? Quelles sont les d\u00e9marches [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qui est responsable lors d\u2019un accident avec un chien\u00a0? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Qui est responsable lors d\u2019un accident avec un chien ? Le propri\u00e9taire du chien ? Le conducteur ? Les deux ? On fait le point !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qui est responsable lors d\u2019un accident avec un chien\u00a0? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Qui est responsable lors d\u2019un accident avec un chien ? Le propri\u00e9taire du chien ? Le conducteur ? Les deux ? On fait le point !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T04:49:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:28+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"5 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/\",\"name\":\"Qui est responsable lors d\\u2019un accident avec un chien\\u00a0? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"datePublished\":\"2024-03-05T04:49:07+00:00\",\"dateModified\":\"2025-07-07T14:02:28+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Qui est responsable lors d\\u2019un accident avec un chien ? Le propri\\u00e9taire du chien ? Le conducteur ? Les deux ? On fait le point !\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/accident-avec-un-chien-qui-est-responsable\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3678"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3678"}],"version-history":[{"count":1,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3678\/revisions"}],"predecessor-version":[{"id":3730,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3678\/revisions\/3730"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3678"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}