{"id":3745,"date":"2024-01-23T05:53:53","date_gmt":"2024-01-23T04:53:53","guid":{"rendered":"https:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/bonus-malus-calcul-2\/"},"modified":"2025-07-07T16:02:28","modified_gmt":"2025-07-07T14:02:28","slug":"bonus-malus-calcul","status":"publish","type":"post","link":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/actualites\/bonus-malus-calcul\/","title":{"rendered":"Comment fonctionne le bonus-malus d\u2019une assurance auto ?"},"content":{"rendered":"<h2>Bonus malus : tout savoir<\/h2>\n<p>En tant que conducteur, vous avez d\u00e9j\u00e0 entendu parler du bonus et du malus par votre assureur. Mais savez-vous \u00e0 quoi il sert et comment il est calcul\u00e9\u00a0? Concr\u00e8tement, le bonus-malus fait partie des crit\u00e8res pour d\u00e9terminer le montant de la prime d\u2019assurance voiture. En effet, les assureurs tiennent compte de ce coefficient qui d\u00e9pend de votre comportement au volant\u00a0! Alors, comment calculer le bonus-malus\u00a0? Quel est son impact sur votre assurance\u00a0? Comment conna\u00eetre son bonus-malus\u00a0? Comment l\u2019am\u00e9liorer\u00a0? On vous dit tout\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<h2>Qu\u2019est ce que le bonus-malus en assurance auto ?<\/h2>\n<p>Le bonus-malus appel\u00e9 aussi CRM (coefficient de r\u00e9duction majoration) est un syst\u00e8me de majoration ou de r\u00e9duction de la prime d\u2019assurance automobile. Les modalit\u00e9s de calcul sont fix\u00e9es par l\u2019\u00c9tat. Ce coefficient est donc mis \u00e0 jour chaque ann\u00e9e en fonction des sinistres responsables ou non qu\u2019aurait subis le conducteur. Par cons\u00e9quent, le montant de cotisation peut augmenter ou baisser en fonction de votre bonus-malus.<\/p>\n<p>En effet, plusieurs crit\u00e8res d\u00e9terminent le tarif annuel d\u2019une assurance voiture comme l\u2019\u00e2ge du conducteur, le v\u00e9hicule, mais aussi votre comportement au volant.<\/p>\n<p>&nbsp;<\/p>\n<h2>Quels sont les v\u00e9hicules exclus du bonus-malus ?<\/h2>\n<p>La plupart des v\u00e9hicules sont concern\u00e9s par le principe du bonus-malus sauf\u00a0:<\/p>\n<ul>\n<li>Les deux ou trois-roues, jusqu\u2019\u00e0 125 cm3 ;<\/li>\n<li>Les transports de pompier, de police, SAMU\u2026 ;<\/li>\n<li>Les\u00a0v\u00e9hicules de collection\u00a0de trente ans et plus ;<\/li>\n<li>Les v\u00e9hicules agricoles\u00a0;<\/li>\n<li>Le mat\u00e9riel forestier\u00a0et de\u00a0travaux publics.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Comment fonctionne le bonus-malus ?<\/h2>\n<p>Le principe du CRM est relativement simple. En l\u2019absence de sinistre responsable, les conducteurs sont r\u00e9compens\u00e9s par un bonus et la prime d\u2019assurance diminue. En revanche, en cas d\u2019accident responsable, ils re\u00e7oivent un malus et par cons\u00e9quent la prime d\u2019assurance augmente.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le bonus assurance auto<\/h3>\n<p>Si le conducteur n\u2019enregistre aucun sinistre responsable sur un an, il obtient un bonus de 5%. Autrement dit, sa prime baisse de 5%.\u00a0Le bonus-malus est alors multipli\u00e9 par un coefficient de 0,95.<\/p>\n<p>Le coefficient maximum qu\u2019un conducteur peut atteindre est 0,50 ce qui correspond \u00e0 14 ans sans sinistre responsable.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le malus assurance auto<\/h3>\n<p>Si le conducteur enregistre un sinistre responsable, il obtient un malus de 25%. Mais si la responsabilit\u00e9 est dite partielle, le malus est minor\u00e9 \u00e0 12,5%. Par cons\u00e9quent, la prime augmente de 25% ou 12,5%.\u00a0Le bonus-malus est alors multipli\u00e9 par un coefficient de 1,25 ou de 1,125.<\/p>\n<p>Le coefficient maximum d\u2019un malus est fix\u00e9 \u00e0 3,50, au-del\u00e0 il n\u2019\u00e9volue plus.<\/p>\n<p><em>Bon \u00e0 savoir\u00a0: Les sinistres non responsables n&rsquo;ont pas d&rsquo;influence sur le bonus-malus. D\u2019autre part, le CRM peut baisser apr\u00e8s 2 ans sans accident responsable.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Comment est calcul\u00e9 le bonus-malus ?<\/h2>\n<p>Le bonus-malus est calcul\u00e9 par l\u2019assureur \u00e0 partir des 12 derniers mois d\u00e9cal\u00e9s de 2 mois par rapport \u00e0 l\u2019\u00e9ch\u00e9ance annuelle de votre contrat auto.<\/p>\n<p><em>Par exemple, l\u2019\u00e9ch\u00e9ance de votre contrat est le 30 avril 2024, la p\u00e9riode de r\u00e9f\u00e9rence prise en compte pour calculer le CRM sera du 1<sup>er<\/sup> mars 2023 au 29 f\u00e9vrier 2024.<\/em><\/p>\n<p>\u00c0 savoir qu\u2019\u00e0 la premi\u00e8re souscription d\u2019un contrat d\u2019assurance auto, le coefficient de d\u00e9part est \u00e9gal \u00e0 1.<\/p>\n<p>&nbsp;<\/p>\n<h3>Comment est calcul\u00e9 le bonus ?<\/h3>\n<p>Comme nous l\u2019avons vu, c&rsquo;est un chiffre qui \u00e9volue suivant si le conducteur subit des sinistres responsables ou non.<\/p>\n<p>Par cons\u00e9quent, chaque ann\u00e9e sans accident responsable, vous b\u00e9n\u00e9ficiez d\u2019une r\u00e9duction de 5% sur le coefficient de l\u2019ann\u00e9e pr\u00e9c\u00e9dente.\u00a0Pour le calcul du bonus-malus, il suffit de multiplier l\u2019ancien coefficient par le nouveau.<\/p>\n<p>&nbsp;<\/p>\n<h4>Tableau r\u00e9capitulatif du bonus-malus<\/h4>\n<p><img class=\"wp-image-56268 size-full\" src=\"https:\/\/www.netvox-assurances.fr\/wp-content\/uploads\/2024\/01\/netvox-assurances-bonus-malus-tableau-explicatif.png\" alt=\"&quot;NetVox\" \/><\/p>\n<p><em>Par exemple, votre prime d\u2019assurance est de 1000 euros la premi\u00e8re ann\u00e9e. Au bout de 12 mois, vous n\u2019avez pas eu d\u2019accident donc vous b\u00e9n\u00e9ficiez d\u2019un coefficient bonus de 0,95. La nouvelle prime se calcule donc ainsi : (1 000 \u20ac x 0,95) = 950 euros. <\/em><\/p>\n<p>En r\u00e9sum\u00e9, au bout de 14 ans sans sinistre responsable, la prime d\u2019assurance de votre v\u00e9hicule baisse de 50 %.<\/p>\n<p>&nbsp;<\/p>\n<h3>Comment est calcul\u00e9 le malus ?<\/h3>\n<p>Le calcul est identique, vous devez multiplier le coefficient de l\u2019ann\u00e9e pr\u00e9c\u00e9dente par le nouveau coefficient.<\/p>\n<p>En effet, plus l\u2019assur\u00e9 a de sinistres responsables avec des tiers, plus le montant de sa cotisation annuelle augmente. Chaque accident responsable totalement ou partiellement entra\u00eene une majoration de 25% du CRM l\u2019ann\u00e9e suivante.<\/p>\n<p>Par exemple, votre coefficient est de 1,25 et vous avez un accident responsable dans l\u2019ann\u00e9e. Votre CRM est multipli\u00e9 par 25% et passe de\u00a01,25 \u00e0 1,56. Votre prime de base \u00e9tait de 1 000 \u20ac la premi\u00e8re ann\u00e9e. Le montant de votre prime maluss\u00e9e va donc \u00e9voluer ainsi\u00a0:<\/p>\n<ul>\n<li>Prime apr\u00e8s le 1<sup>er<\/sup> sinistre\u00a0: 1 000 \u20ac x 1,25 = 1 250 \u20ac\u00a0;<\/li>\n<li>Prime apr\u00e8s le 2\u00e9me sinistre\u00a0: 1 000 \u20ac x 1,56 = 1 560 \u20ac.<\/li>\n<\/ul>\n<p>Attention, la prime peut \u00eatre encore plus \u00e9lev\u00e9e si vous \u00eates jeune conducteur, et ce m\u00eame si le calcul du bonus-malus est identique, quel que soit l\u2019\u00e2ge du conducteur. Mais les assureurs peuvent appliquer une surprime s\u2019ils consid\u00e8rent que vous \u00eates un conducteur \u00e0 risque. De m\u00eame, vous pouvez voir votre assurance auto r\u00e9sili\u00e9e si vous avez eu trop de sinistres responsables au cours des derni\u00e8res ann\u00e9es.<\/p>\n<p><em>Bon \u00e0 savoir\u00a0: Si vous avez un bonus de 0,50 depuis au moins 3 ans, vous n\u2019aurez pas de malus appliqu\u00e9 en cas de 1<sup>er<\/sup> accident responsable.<\/em><\/p>\n<p>&nbsp;<\/p>\n<h2>Combien de temps pour r\u00e9cup\u00e9rer un bonus ?<\/h2>\n<p>Vous pouvez r\u00e9cup\u00e9rer votre bonus apr\u00e8s plusieurs ann\u00e9es sans sinistre responsable ou partiellement responsable. Si par exemple, vous avez un bonus-malus de 1,25, il vous faudra 5 ans pour revenir \u00e0 votre coefficient initial.<\/p>\n<p>Mais il existe ce que l\u2019on appelle la r\u00e8gle de descente rapide du malus d\u2019assurance auto. Concr\u00e8tement, il est possible de revenir \u00e0 un coefficient de 1 apr\u00e8s deux ans sans sinistre responsable.<\/p>\n<p>Par cons\u00e9quent, quel que soit le malus, au bout de deux ans, le coefficient applicable ne peut \u00eatre sup\u00e9rieur \u00e0 1. Ce qui m\u00e9caniquement fait baisser le prix de l\u2019assurance voiture\u00a0!<\/p>\n<p>&nbsp;<\/p>\n<h2>Que devient le bonus-malus en cas d&rsquo;assurance ?<\/h2>\n<p>Vous conservez votre coefficient m\u00eame si vous changez d\u2019assurance ou de voiture. En effet, il est transf\u00e9r\u00e9 automatiquement.<\/p>\n<p>D\u2019autre part, si vous vendez un v\u00e9hicule et d\u00e9cidez de ne pas en reprendre un dans l\u2019imm\u00e9diat, votre contrat d\u2019assurance est interrompu. Deux cas de figure se pr\u00e9sentent alors\u00a0:<\/p>\n<ul>\n<li><strong>Interruption de l\u2019assurance auto inf\u00e9rieure \u00e0 3 mois<\/strong>: Vous b\u00e9n\u00e9ficiez d\u2019une \u00e9volution de 5% de votre bonus lors de la souscription de votre contrat, si vous n\u2019avez eu aucun sinistre responsable dans l\u2019ann\u00e9e.<\/li>\n<li><strong>Interruption de l\u2019assurance auto\u00a0sup\u00e9rieure \u00e0 3 mois<\/strong>: Vous conservez le bonus-malus, mais l&rsquo;assureur peut aussi vous consid\u00e9rer comme un nouveau conducteur si la dur\u00e9e de l&rsquo;interruption est tr\u00e8s longue.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2>Comment conna\u00eetre votre coefficient bonus-malus ?<\/h2>\n<p>Chaque ann\u00e9e, votre assureur vous d\u00e9livre un relev\u00e9 d\u2019informations \u00e0 l\u2019\u00e9ch\u00e9ance de votre contrat. Ce document mentionne les informations suivantes\u00a0:<\/p>\n<ul>\n<li>Le coefficient de r\u00e9duction majoration,<\/li>\n<li>La liste des sinistres responsables au cours des 5 derni\u00e8res ann\u00e9es.<\/li>\n<\/ul>\n<p>Notez que vous pouvez demander ce document \u00e0 tout moment de l\u2019ann\u00e9e. En effet, ce relev\u00e9 est indispensable pour changer de compagnie d\u2019assurance.<\/p>\n<p>En r\u00e9sum\u00e9, le CRM est un syst\u00e8me qui r\u00e9compense ou p\u00e9nalise les assur\u00e9s pour leur conduite en augmentant ou baissant le montant de la prime d\u2019assurance.<\/p>\n<p>Bien que le calcul soit identique pour toutes les compagnies, la prime de base est fix\u00e9e librement par les assureurs. Par cons\u00e9quent, il reste possible de comparer les tarifs des assurances auto en fonction de votre bonus-malus afin de choisir la meilleure offre !<\/p>\n<p>&nbsp;<\/p>\n<p>[vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text][\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<p><strong>Ces articles pourraient vous int\u00e9resser :<\/strong><\/p>\n<ul>\n<li>Assurance auto : comment calculer le bonus malus\u2009?<\/li>\n<li>Quel bonus pour les conducteurs occasionnels\u00a0?<\/li>\n<li>Le bonus malus du jeune conducteur en assurance auto<\/li>\n<li>D\u00e9couvrez comment conna\u00eetre son bonus assurance auto<\/li>\n<li>Conducteur secondaire : quel bonus pour l\u2019assurance auto<\/li>\n<li>Assurance auto bonus : covoiturage ou auto partage ?<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonus malus : tout savoir En tant que conducteur, vous avez d\u00e9j\u00e0 entendu parler du bonus et du malus par votre assureur. Mais savez-vous \u00e0 quoi il sert et comment il est calcul\u00e9\u00a0? Concr\u00e8tement, le bonus-malus fait partie des crit\u00e8res pour d\u00e9terminer le montant de la prime d\u2019assurance voiture. En effet, les assureurs tiennent compte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[23],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment fonctionne le bonus-malus d\u2019une assurance auto ? - Netvox - Courtier 3<\/title>\n<meta name=\"description\" content=\"Comment est calcul\u00e9 le bonus ainsi que le malus de votre assurance auto ? On vous explique tout ! Retrouvez notre tableau explicatif.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment fonctionne le bonus-malus d\u2019une assurance auto ? - Netvox - Courtier 3\" \/>\n<meta property=\"og:description\" content=\"Comment est calcul\u00e9 le bonus ainsi que le malus de votre assurance auto ? On vous explique tout ! Retrouvez notre tableau explicatif.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/\" \/>\n<meta property=\"og:site_name\" content=\"Netvox - Courtier 3\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-23T04:53:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-07-07T14:02:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.netvox-assurances.fr\/wp-content\/uploads\/2024\/01\/netvox-assurances-bonus-malus-tableau-explicatif.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"7 minutes\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"Netvox - Courtier 3\",\"description\":\"Site courtier : template 3\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.netvox-assurances.fr\/wp-content\/uploads\/2024\/01\/netvox-assurances-bonus-malus-tableau-explicatif.png\",\"contentUrl\":\"https:\/\/www.netvox-assurances.fr\/wp-content\/uploads\/2024\/01\/netvox-assurances-bonus-malus-tableau-explicatif.png\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#webpage\",\"url\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/\",\"name\":\"Comment fonctionne le bonus-malus d\\u2019une assurance auto ? - Netvox - Courtier 3\",\"isPartOf\":{\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#primaryimage\"},\"datePublished\":\"2024-01-23T04:53:53+00:00\",\"dateModified\":\"2025-07-07T14:02:28+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Comment est calcul\\u00e9 le bonus ainsi que le malus de votre assurance auto ? On vous explique tout ! Retrouvez notre tableau explicatif.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"url\":\"http:\/\/www.datastore-3.com\/netvox-courtier-3\/\",\"name\":\"home\"}},{\"@type\":\"ListItem\",\"position\":2,\"item\":{\"@id\":\"https:\/\/www.netvox-assurances.fr\/communication\/actualites\/bonus-malus-calcul\/#webpage\"}}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3745"}],"collection":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/comments?post=3745"}],"version-history":[{"count":0,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/posts\/3745\/revisions"}],"wp:attachment":[{"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/media?parent=3745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/categories?post=3745"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.datastore-3.com\/netvox-courtier-3\/wp-json\/wp\/v2\/tags?post=3745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}